{"id":854,"date":"2011-05-07T00:38:51","date_gmt":"2011-05-06T22:38:51","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=854"},"modified":"2011-05-07T00:38:51","modified_gmt":"2011-05-06T22:38:51","slug":"hay-miedo-frente-al-macro-o-mini-botellon-miedo-a-perder-votos","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/05\/07\/hay-miedo-frente-al-macro-o-mini-botellon-miedo-a-perder-votos\/","title":{"rendered":"\u00bfHay miedo frente al macro o mini botell\u00f3n? \u00bfMiedo a perder votos?"},"content":{"rendered":"<p>El olor del campus esta ma\u00f1ana no era precisamente el de una paella de le\u00f1a. Un fuerte hedor a or\u00edn, mezclado con el alcohol y las decenas de bolsas de basura acumuladas se han apoderado de las instalaciones de parte de la Universidad Polit\u00e9cnica. \u00bfC\u00f3mo nos van a dar la excelencia?<\/p>\n<p>Estos &#8220;estudiantes&#8221; son una verg\u00fcenza y quienes consentimos esto tambi\u00e9n. Es evidente que las crisis no vienen solas y est\u00e1 actual se lleva &#8220;cociendo&#8221; alg\u00fan tiempo. Imaginemos que un dispositivo policial pudiera evitarlo \u00bfse perder\u00edan votos? Creo que no. Y si se perdiesen dar\u00eda igual. No es concebible que con los recursos que ponemos en las Universidades P\u00fablicas y el coste por alumno el resultado es que la respuesta de la sociedad ( el conjunto de los otros que representados por el Municipio, el Consell, la Delegaci\u00f3n de Gobierno y los \u00f3rganos rectores de la propia Universidad sea el dar la espalda y re\u00edrse de estas cosas clasificandolas como &#8220;de jovenes&#8221;).<\/p>\n<p>No deja de llamarme la atenci\u00f3n que yo no me pueda fumar un cigarrillo en un bar con reservado al efecto en su d\u00eda y anoche centenares de &#8220;tipos&#8221; se meen , se caguen y griten sin dejar dormir a los habitantes de la zona y se vayan a casa creyendo que han conquistado la libertad&#8230;y los que que quieren ser votados pegando cartelitos. Buenas noches o d\u00edas como quieran.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El olor del campus esta ma\u00f1ana no era precisamente el de una paella de le\u00f1a. Un fuerte hedor a or\u00edn, mezclado con el alcohol y las decenas de bolsas de basura acumuladas se han apoderado de las instalaciones de parte de la Universidad Polit\u00e9cnica. \u00bfC\u00f3mo nos van a dar la excelencia? Estos &#8220;estudiantes&#8221; son una [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-854","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=854"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/854\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}