{"id":865,"date":"2011-05-13T12:27:34","date_gmt":"2011-05-13T10:27:34","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=865"},"modified":"2011-05-13T12:27:34","modified_gmt":"2011-05-13T10:27:34","slug":"tiene-usted-algo-que-lo-diferencie-de-otro-si-sera-pasto-de-los-realitissic","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/05\/13\/tiene-usted-algo-que-lo-diferencie-de-otro-si-sera-pasto-de-los-realitissic\/","title":{"rendered":"\u00bfTiene usted algo que lo diferencie de otro? Si. Ser\u00e1 pasto de los realitis(sic)"},"content":{"rendered":"<p>Los medios de comunicaci\u00f3n se han apresurado a bautizarle como el ni\u00f1o magn\u00e9tico despu\u00e9s de haber visto que era capaz de sostener en su torso un variopinto surtido de quincalla met\u00e1lica.<\/p>\n<p>Esta noticia parcelada por mi tiene que ver con el extra\u00f1o atractivo que mantenemos por aquellos que se diferencian de nosotros con alguna extra\u00f1a cualidad como aqu\u00ed es el caso.Le llaman el ni\u00f1o magn\u00e9tico y ahora , sus padres, dicen que hasta parece curar.Ivan es serbio y \u00a0tiene el destino marcado.Ser\u00e1 objeto de uso y abuso y cientos de enfermos imaginarios o no, ir\u00e1n a que se les cure con su poderes magn\u00e9ticos.<\/p>\n<p>Ya se sabe que en \u00e9pocas de crisis nos agarramos\u00a0 a un clavo ardiendo. Ivan el Serbio, Ivan el magn\u00e9tico ayudar\u00e1 con su magnetismo a sacar a sus padres de la pobreza pronto. Se pasar\u00e1 y vendr\u00e1n otros magn\u00e9ticos. Estamos, en ciertas cosas, en el Paleol\u00edtico.Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los medios de comunicaci\u00f3n se han apresurado a bautizarle como el ni\u00f1o magn\u00e9tico despu\u00e9s de haber visto que era capaz de sostener en su torso un variopinto surtido de quincalla met\u00e1lica. Esta noticia parcelada por mi tiene que ver con el extra\u00f1o atractivo que mantenemos por aquellos que se diferencian de nosotros con alguna extra\u00f1a [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-865","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=865"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/865\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}