{"id":943,"date":"2011-07-05T07:57:28","date_gmt":"2011-07-05T05:57:28","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=943"},"modified":"2011-07-05T07:57:28","modified_gmt":"2011-07-05T05:57:28","slug":"usted-llora-cuando-y-por-que-esa-es-la-cuestion","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/07\/05\/usted-llora-cuando-y-por-que-esa-es-la-cuestion\/","title":{"rendered":"\u00bfUsted llora? \u00bfCuando y por qu\u00e9? Esa es la cuesti\u00f3n"},"content":{"rendered":"<p>LA CHISPA<\/p>\n<p>Las l\u00e1grimas<\/p>\n<p>Carlos Pajuelo de Arcos<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 En el discurso repetitivo del Estado de la Naci\u00f3n, el pronunciado por el Jefe del Ejecutivo se notaron algunas chispas de emoci\u00f3n lacrimosa en las pupilas azules que me recordaban\u00a0 al otrora calificado con \u201cbambi\u201d de acero por aquel Guerra que nos divert\u00eda y facilitaba titulares.<\/p>\n<p>El Jefe del Ejecutivo- como a la saz\u00f3n parece que hay que llamarle y que, por cierto, tiene el nombre un cierto tufo a liquidaci\u00f3n, a ejecuci\u00f3n, aunque esa ejecuci\u00f3n lo sea de los principios que pueden haberse jurado y de los cuales ahora se abjura con base en una conspiraci\u00f3n financiera internacional. El Jefe, repito, parec\u00eda llorar.<\/p>\n<p>A m\u00ed me gustar\u00eda penetrar como una silenciosa daga de la verdad en el cerebro de Bambi en el momento que relato y saber, a ciencia cierta, el porqu\u00e9 de ese chispazo lloroso y de nene al que le quitan un juguete.<\/p>\n<p>\u00bfEs la rabia, es el dolor, es la nostalgia, es el futuro personal, es su familia que estaba all\u00ed en la tribuna de invitados?<\/p>\n<p>\u00bfRabia? Puede ser que lo fuera por pensar que es un incomprendido incluso por quienes forman parte de su propio equipo que ya se apresuran a repartirse el bot\u00edn que queda y el so\u00f1ado por si volvieran a disponer del Tesoro.<\/p>\n<p>Se denomina \u201cganga\u201d a aquel tesoro que uno encuentra en el fondo marino y que debe pertenecer a alg\u00fan naufragio y hay quienes dicen que no, que a eso se llama pecio. \u00a1Qu\u00e9 m\u00e1s da lenguaje imperfecto!<\/p>\n<p>El caso es que, supongo, cuando uno tiene un saco de dinero que como dec\u00eda, una ex -ministra hoy el en Senado- usted me dir\u00e1 para que sirve- el \u201cdinero no es de nadie\u201d debe dar rabia no poder dar orden de disponer del mismo para, quien sabe que talante, que Alianza de Civilizaciones.<\/p>\n<p>\u00bfSer\u00e1, digo, una mezcla de rabia, malentendido, incomprensi\u00f3n, orgullo herido y una muestra familiar de sensibilidad que puede darle a uno r\u00e9ditos cari\u00f1osos?<\/p>\n<p>A m\u00ed no me importa ver a un hombre llorar, es humano y est\u00e1 en la naturaleza de las cosas. Lo que me importa es el porqu\u00e9 y me importa cuando ese hombre lo es p\u00fablico y sobre \u00e9l descansa el peso de la purpura, democr\u00e1tica o no. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA CHISPA Las l\u00e1grimas Carlos Pajuelo de Arcos \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 En el discurso repetitivo del Estado de la Naci\u00f3n, el pronunciado por el Jefe del Ejecutivo se notaron algunas chispas de emoci\u00f3n lacrimosa en las pupilas azules que me recordaban\u00a0 al otrora calificado con \u201cbambi\u201d de acero por aquel Guerra que nos divert\u00eda y facilitaba titulares. [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-943","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=943"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/943\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}