{"id":962,"date":"2011-07-17T10:53:14","date_gmt":"2011-07-17T08:53:14","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=962"},"modified":"2011-07-17T10:53:14","modified_gmt":"2011-07-17T08:53:14","slug":"somos-unos-guarros-con-lo-que-no-consideramos-nuestro","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/07\/17\/somos-unos-guarros-con-lo-que-no-consideramos-nuestro\/","title":{"rendered":"\u00bfSomos unos guarros con lo que no consideramos nuestro?"},"content":{"rendered":"<p>Un numeroso grupo de personas vagara por el Saler con bolsas de basura en el d\u00eda de hoy. Son vecinos que van a limpiar lo que otros dejan. Es el caso de un amigo que presenci\u00f3 una discusi\u00f3n poque un excursionsista lleg\u00f3\u00a0m\u00e1s tarde de lo habitual a su sitio de toda la vida y se enfad\u00f3 con \u00e9l.Le dec\u00eda: &#8220;Oiga usted que yo vengo con mi familia aqu\u00ed desde hace m\u00e1s de cinco a\u00f1os&#8230;fijese lo limpio que est\u00e1.Lo hemos hecho nosotros&#8221; y ese argumento es m\u00e1ximo.Solo cuando algo lo consideramos nuestro lo cuidamos-en general claro.<\/p>\n<p>\u00bfPor qu\u00e9 tiramos papeles al suelo? Es lo del ciudadano suizo que en silencio y a un amigo m\u00edo,tambi\u00e9n, le devolvi\u00f3 la cajetilla vac\u00eda que hab\u00eda tirado al suelo en Lucerna sin decir nada y sigui\u00f3 andando. Mi amigo no dijo nada.Solo las tira por la ventanilla en Espa\u00f1a. !Un guarro cobard\u00f3n!.Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un numeroso grupo de personas vagara por el Saler con bolsas de basura en el d\u00eda de hoy. Son vecinos que van a limpiar lo que otros dejan. Es el caso de un amigo que presenci\u00f3 una discusi\u00f3n poque un excursionsista lleg\u00f3\u00a0m\u00e1s tarde de lo habitual a su sitio de toda la vida y se [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-962","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=962"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/962\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}