{"id":983,"date":"2011-07-29T07:54:17","date_gmt":"2011-07-29T05:54:17","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=983"},"modified":"2011-07-29T07:54:17","modified_gmt":"2011-07-29T05:54:17","slug":"habra-que-crear-patrullas-o-somatenes-vecinales-en-el-perello-valencia-ha-de-ser-antes-de-otono","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/07\/29\/habra-que-crear-patrullas-o-somatenes-vecinales-en-el-perello-valencia-ha-de-ser-antes-de-otono\/","title":{"rendered":"Habr\u00e1 que crear patrullas o somatenes vecinales en El Perello-Valencia? Ha de ser antes de oto\u00f1o"},"content":{"rendered":"<p>Es el caso que en el Perello ,dependiente administrativamente del Ayuntamiento de Sueca, en verano se \u00a0multiplica su poblaci\u00f3n y cuenta, a efectos de seguridad con un solo agente de la Polic\u00eda Local que por cierto, est\u00e1 de vacaciones ahora. Yo s\u00e9 que es dif\u00edcil ponerse de acuerdo con los turnos-pero en este caso como solo hay \u00a0un polic\u00eda adscrito a esa pedan\u00eda- por cierto y aunque \u00a0no venga a cuento que tomates para ensalada, sigamos-la cosa parecer\u00eda sencilla, pero en una especie de tripartito o coalici\u00f3n, en \u00a0el Ayuntamiento no se ponen de acuerdo porque es, al parecer, dif\u00edcil encontrar un sustituto.<\/p>\n<p>Yo les digo que no hace falta que se Poirot o Sherlock , ni Bond James. Solo es que debe estar cuando m\u00e1s gente hay y adem\u00e1s de \u00a0uno hay que poner varios , zonificar, guardar las casas de los vecinos que pagan sus impuestos a precio de oro.<\/p>\n<p>Alguien puso un cartel en la puerta del local municipal de la Polic\u00eda ausente que dice &#8220;cerrado por vacaciones e incompetencia pol\u00edtica&#8221; m\u00e1s o menos Veo por las noches en mis sue\u00f1os perelllonenses a un nutrido o apretado grupo de valientes vecinos con sus linternas temblorosas recorrer rambisticamente las calles de la ciudadela del mar. No lo veo claro y debe ser que de noche todos los gatos son pardos. Pueden cometerse errores. Contraten serenos con walkies mientras tanto, adem\u00e1s de beber agua para los debates municipales. Mojense y den vacaciones en invierno al polic\u00eda adscrito, digo yo.<\/p>\n<p>\u00bfHan hablado con la llamada autoridad competente? \u00bf\u00bfD\u00f3nde vive ese individu@? Comprenle un apartamento en el Perello y a lo mejor se lleva una patrulla consigo para evitar que &#8220;los nenes&#8221; se caigan al agua del peque\u00f1o puerto. Buenos d\u00edas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es el caso que en el Perello ,dependiente administrativamente del Ayuntamiento de Sueca, en verano se \u00a0multiplica su poblaci\u00f3n y cuenta, a efectos de seguridad con un solo agente de la Polic\u00eda Local que por cierto, est\u00e1 de vacaciones ahora. Yo s\u00e9 que es dif\u00edcil ponerse de acuerdo con los turnos-pero en este caso como [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-983","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=983"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/983\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}