{"id":988,"date":"2011-08-01T09:18:56","date_gmt":"2011-08-01T07:18:56","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=988"},"modified":"2011-08-01T09:18:56","modified_gmt":"2011-08-01T07:18:56","slug":"iria-usted-desnudo-sobre-la-bicicleta-como-en-portland-para-eso-hay-que-tener-cuerpodigo","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/08\/01\/iria-usted-desnudo-sobre-la-bicicleta-como-en-portland-para-eso-hay-que-tener-cuerpodigo\/","title":{"rendered":"\u00bfIr\u00eda usted desnudo sobre la bicicleta como en Portland? Para eso hay que tener cuerpo,digo"},"content":{"rendered":"<p>Le\u00ed un estupendo reportaje sobre Portland el otro d\u00eda de la pluma de Mercedes Gallego y tan es as\u00ed que me han dado ganas de irme a Portland. \u00bfIrme como si abandonase el Mediterraneo?. No. Irme solo un poquito y ver la ciudad que , seg\u00fan Gallego, es la que ha ganado la partida a al ecolog\u00eda, al placer de vivir y la bonhom\u00eda de sus gentes. Ser\u00e1 digo como una especie de Para\u00edso perdido de Milton, por decir algo. Una especie de gloria a preservar.<\/p>\n<p>Las gentes circulan mucho en bici y una vez al a\u00f1o se regocijan , ellos y los mirones, en pasearse montados en su bici como vinieron al mundo o casi.<\/p>\n<p>Con el calor que hace aqu\u00ed no estar\u00eda dem\u00e1s que se pudiera hacer aqu\u00ed. Ir en bolas, que se llama, tiene eun inconveniente y es que no todas las bolas del respetable son el David de Miguel Angel o las curvas de la m\u00edtica Marilyn. Est\u00e1 claro. No somos iguales. Yo no estoy ahora para &#8220;bolearme&#8221; p\u00fablicamente sobre la bici&#8230;y sobre nada.Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le\u00ed un estupendo reportaje sobre Portland el otro d\u00eda de la pluma de Mercedes Gallego y tan es as\u00ed que me han dado ganas de irme a Portland. \u00bfIrme como si abandonase el Mediterraneo?. No. Irme solo un poquito y ver la ciudad que , seg\u00fan Gallego, es la que ha ganado la partida a [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-988","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=988"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/988\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}