{"id":997,"date":"2011-08-06T14:37:02","date_gmt":"2011-08-06T12:37:02","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=997"},"modified":"2011-08-06T14:37:02","modified_gmt":"2011-08-06T12:37:02","slug":"se-lleva-usted-bien-con-su-companero-de-trabajo-no-ojo","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/08\/06\/se-lleva-usted-bien-con-su-companero-de-trabajo-no-ojo\/","title":{"rendered":"\u00bfSe lleva usted bien con su compa\u00f1ero de trabajo? No. Ojo."},"content":{"rendered":"<p>Seg\u00fan un estudio de la Universidad de Tel Aviv (Israel),\u00a0<strong>llevarse bien con los compa\u00f1eros de trabajo tiene beneficios sobre la salud a largo plazo<\/strong>. Concretamente, Sharon Toker y su equipo han demostrado que los empleados que creen tener apoyo de sus iguales en el trabajo suelen ser\u00a0<strong>m\u00e1s longevos<\/strong>.<\/p>\n<p>A partir de ahora usted debe hacer intentos en llevarse bien con MariPili o con el pijo de Borja Andr\u00e9s, un decir. Y todo debe hacerlo por su bien, por cuerpo, por vida y todo, aunque\u00a0sepa usted que MariPili es m\u00e1s tonta que pichote o pichota ( igualdad de\u00a0genero) o que Borja es m\u00e1s pijo que el inventor de la estufa para los d\u00edas calurosos del desierto.<\/p>\n<p>Usted\u00a0debe\u00a0amar a troche y moche para asegurarse una vejez pensionada( si llega la Seguridad Social a no reventar\u00a0antes,claro). Una sonrisa blanca , un destello en la mirada un caf\u00e9 asqueroso de maquina a tiempo; todo, todo contribuye al \u00e9xito y a la paz oficinesca y a la paz mundial.<\/p>\n<p>La vejez, se lo aseguro, es complicada aveces.&#8221;experiencia personal dixit&#8221; pero he le\u00eddo que hay tipos que sobrepasan con mucho mi edad y ah\u00ed est\u00e1n- como la Puerta de Alcal\u00e1 ( ahora debe usted entonar en plan\u00a0coro\u00a0la cancioncita) \u00bfPuede que la clave est\u00e9 en que se llevaron bien con sus compa\u00f1eros de oficina? \u00bfPuede que nunca tuvieron oficina y por tanto lo anterior es una entelequia? Me inclino por esto \u00faltimo. Por si es verdad no insulte a sus\u00a0compa\u00f1eros\u00a0de comunidad, familia, municipio y sindicato . Genera inquietud,arrugas,dolor de\u00a0estomago\u00a0y al final\u00a0acabas\u00a0jodidamente muerto. Buenos d\u00edas. Adios MariPili me encantas y tu Borja amigo vales mucho. Con eso he ganado no solo el cielo,si existe, sino cuatro a\u00f1os o m\u00e1s de vieja vida<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan un estudio de la Universidad de Tel Aviv (Israel),\u00a0llevarse bien con los compa\u00f1eros de trabajo tiene beneficios sobre la salud a largo plazo. Concretamente, Sharon Toker y su equipo han demostrado que los empleados que creen tener apoyo de sus iguales en el trabajo suelen ser\u00a0m\u00e1s longevos. A partir de ahora usted debe hacer [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-997","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=997"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/997\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}