{"id":511,"date":"2020-04-07T18:23:12","date_gmt":"2020-04-07T18:23:12","guid":{"rendered":"https:\/\/blogs.lasprovincias.es\/empleoytalento\/?p=511"},"modified":"2020-04-07T18:23:12","modified_gmt":"2020-04-07T18:23:12","slug":"resistire-mos-desde-el-talento","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/empleoytalento\/2020\/04\/07\/resistire-mos-desde-el-talento\/","title":{"rendered":"Resistir\u00e9-MOS desde el Talento"},"content":{"rendered":"<p>Resistir\u00e9-MOS desde el Talento.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Quiero compartir con vosotr@s un videoclip musical que hemos hecho 19 amigos y conferenciantes para apoyar la situaci\u00f3n tan complicada actual que estamos viviendo. Con la canci\u00f3n Resistir\u00e9 en versi\u00f3n instrumental hemos puesto nuestras mejores voces (est\u00e1 claro que los nuestro son las conferencias y no cantar jaja). Os mandamos a tod@s un mensaje de solidaridad, unidad, esperanza y altruismo.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Jose Maria Gasalla #IsmaelQuintanilla Jos\u00e9 Aguilar Fernando \u00c1lvarez Gonz\u00e1lez Jos\u00e9 Luis Llorente Gento Carlos Andreu Pintado Gustavo Piera Marisa Salanova Santiago Vazquez Santiago Garc\u00eda Sebastian Alvaro Xesco Espar Alonso Pulido JUAN PLANES MESTRE Marcos \u00c1lvarez Belen Varela Romero V\u00edctor Aleixandre Jose Luis Herranz<\/p>\n<p><iframe loading=\"lazy\" title=\"Resistire\u0301-mos desde el Talento\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/GPUVu8AB8Oo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Resistir\u00e9-MOS desde el Talento.\u00a0 Quiero compartir con vosotr@s un videoclip musical que hemos hecho 19 amigos y conferenciantes para apoyar la situaci\u00f3n tan complicada actual que estamos viviendo. Con la canci\u00f3n Resistir\u00e9 en versi\u00f3n instrumental hemos puesto nuestras mejores voces (est\u00e1 claro que los nuestro son las conferencias y no cantar jaja). Os mandamos a [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-511","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/empleoytalento\/wp-json\/wp\/v2\/posts\/511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/empleoytalento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/empleoytalento\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/empleoytalento\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/empleoytalento\/wp-json\/wp\/v2\/comments?post=511"}],"version-history":[{"count":1,"href":"https:\/\/blogs.lasprovincias.es\/empleoytalento\/wp-json\/wp\/v2\/posts\/511\/revisions"}],"predecessor-version":[{"id":512,"href":"https:\/\/blogs.lasprovincias.es\/empleoytalento\/wp-json\/wp\/v2\/posts\/511\/revisions\/512"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/empleoytalento\/wp-json\/wp\/v2\/media?parent=511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/empleoytalento\/wp-json\/wp\/v2\/categories?post=511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/empleoytalento\/wp-json\/wp\/v2\/tags?post=511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}