{"id":170,"date":"2010-05-27T07:35:11","date_gmt":"2010-05-27T07:35:11","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/mariajosepou\/?p=170"},"modified":"2010-05-27T07:35:11","modified_gmt":"2010-05-27T07:35:11","slug":"en-modo-santo-tomas","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2010\/05\/27\/en-modo-santo-tomas\/","title":{"rendered":"En modo \u201cSanto Tom\u00e1s\u201d"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2010\/05\/sony-ericsson-w205-creamy-white.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-171\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2010\/05\/sony-ericsson-w205-creamy-white.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Acabo de cambiar de m\u00f3vil con el sistema de puntos de Vodafone. Pero los puntos no s\u00e9 si son una ventaja para proporcionarme un m\u00f3vil a menos precio o un truco para introducir en el mercado aparatos inservibles.<\/p>\n<p style=\"text-align: justify\">El m\u00edo es uno de \u00e9sos. La bater\u00eda dura apenas una conversaci\u00f3n; la carcasa parece de juguete y en lugar de ser mejor \u00e9ste que la versi\u00f3n anterior, es peor. Por no poder no puedo ni pasar las fotos del antiguo porque son demasiado buenas. Cuando he querido averiguar por qu\u00e9 me he encontrado con la misma clave: \u201cMade in China\u201d. En efecto, parece de los chinos. Del chino de la esquina.<\/p>\n<p style=\"text-align: justify\">No es que est\u00e9 enfadada. Estoy estupefacta. Me cuesta creer que una marca tan consolidada como Sony Ericsson enga\u00f1e as\u00ed a sus usuarios. De hecho, mi hip\u00f3tesis es que se trata de una falsificaci\u00f3n, como los bolsos de Tous que venden en el mercadillo, y Sony no lo sabe. De otro modo, la alternativa es desoladora: las grandes marcas apuestas por los productos basura para abaratar.<\/p>\n<p style=\"text-align: justify\">La verdad es que estoy harta de esos \u201clow cost\u201d. Una cosa es no ser muy exigente con lo que se compra (yo, en m\u00f3viles no lo soy porque no duran nada) y otra, que tengamos que tragar con ruedas de molino. De molino chino, para ser exactos.<\/p>\n<p style=\"text-align: justify\">Durante a\u00f1os hemos presumido de unos est\u00e1ndares de calidad que hac\u00edan distinto el producto espa\u00f1ol de su mala imitaci\u00f3n asi\u00e1tica, pero ahora tengo la sensaci\u00f3n de que el mercado se est\u00e1 reduciendo a ese nivel \u00ednfimo reservado, hasta hace poco, solo a los aficionados a las tiendas multiprecio de Lin Chiao.<\/p>\n<p style=\"text-align: justify\">A eso se une la tendencia de algunas compa\u00f1\u00edas que incitan a comprar por Internet. Supongo que con ello recortan gastos. M\u00e1s vale pagar a un mensajero que al encargado de la tienda, el alquiler del local, la luz, agua o contribuci\u00f3n urbana.<\/p>\n<p style=\"text-align: justify\">Sin embargo, yo estoy en proceso regresivo. Despu\u00e9s del fiasco del m\u00f3vil, no compro otro por Internet. He decidido ponerme en modo \u201cSanto Tom\u00e1s\u201d. Si no lo toco no lo creo. Y ya hablar\u00e9 de Camps otro d\u00eda.<\/p>\n<p style=\"text-align: justify\">\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Acabo de cambiar de m\u00f3vil con el sistema de puntos de Vodafone. Pero los puntos no s\u00e9 si son una ventaja para proporcionarme un m\u00f3vil a menos precio o un truco para introducir en el mercado aparatos inservibles. El m\u00edo es uno de \u00e9sos. La bater\u00eda dura apenas una conversaci\u00f3n; la carcasa parece de juguete [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[65],"class_list":["post-170","post","type-post","status-publish","format-standard","hentry","category-arsenico-por-diversion","tag-economia"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=170"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/170\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}