{"id":1796,"date":"2011-09-25T09:08:57","date_gmt":"2011-09-25T09:08:57","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/mariajosepou\/?p=1796"},"modified":"2011-09-25T09:08:57","modified_gmt":"2011-09-25T09:08:57","slug":"animales-en-valencia","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2011\/09\/25\/animales-en-valencia\/","title":{"rendered":"Animales en Valencia"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2011\/09\/P1050556_22.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-1797 alignleft\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2011\/09\/P1050556_22.jpg\" alt=\"\" width=\"300\" height=\"195\" \/><\/a>Hasta ayer pensaba que los animales que mejor viv\u00edan en Valencia era los del Bioparc. O sea, los de un zoo. Sin embargo, ayer los activistas de Igualdad Animal dijeron que no. <a href=\"http:\/\/www.lasprovincias.es\/prensa\/20110925\/valencia\/protesta-contra-zoos-junto-20110925.html\" rel=\"external nofollow\">Que ni esos<\/a>.<\/p>\n<p style=\"text-align: justify\">Lo pensaba porque, leyendo las ordenanzas municipales sobre animales dom\u00e9sticos, vi que un perro en Valencia tiene dificultades para ser un perro equilibrado. Si cumple la ley.<\/p>\n<p style=\"text-align: justify\">El <a href=\"http:\/\/www.eurekan.es\/\" rel=\"external nofollow\">educador de mis perros<\/a> me ha ense\u00f1ado que la eliminaci\u00f3n del estr\u00e9s que padec\u00eda &#8216;Whisky&#8217; y el equilibrio de un animal requieren andar suelto de vez en cuando, correr en la naturaleza y pasear por ella a diario. Es l\u00f3gico: es un animal. Los animales necesitan vivir en un entorno natural y ya que los sacamos de \u00e9l cuando los domesticamos, lo mejor es hacerles volver lo m\u00e1s posible.<\/p>\n<p style=\"text-align: justify\">Sin embargo aunque la Generalitat obliga a las autoridades a proporcionar bienestar a los animales, los que viven en Valencia tienen prohibido ir sueltos por la calle y por los jardines, incluido el cauce del Turia. Solo les queda el pasillo de casa o los &#8216;pipicanes&#8217; en donde no caben tres perros al mismo tiempo. Tampoco pueden ba\u00f1arse en balsas como las que hay por el antiguo cauce ni fuentes ni playas; no pueden pisar la hierba de los jardines ni pueden &#8216;marcar&#8217; el territorio, como hacen los machos, en los alcorques de los \u00e1rboles.<\/p>\n<p style=\"text-align: justify\">En una palabra, solo pueden vivir atados, salvo en los 90 metros cuadrados en los que los confinamos para disfrutar de ellos. O sea los due\u00f1os que cumplen la ley los someten a una vida perra, nunca mejor dicho, excepto que puedan disfrutar de un chalet.<\/p>\n<p style=\"text-align: justify\">Esa es la raz\u00f3n por la que cre\u00eda que los animales del Bioparc eran los \u00fanicos realmente libres. Para ellos, al menos, hay una reproducci\u00f3n de su entorno natural donde no tienen que estar atados. Sin embargo, los de Igualdad Animal se manifestaron para hacernos ver que eso tambi\u00e9n es un encierro. Es coherente con la ciudad. Valencia no es ciudad para animales.<\/p>\n<p style=\"text-align: justify\">Foto: Whisky y Solete frente al Palau de les Arts<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hasta ayer pensaba que los animales que mejor viv\u00edan en Valencia era los del Bioparc. O sea, los de un zoo. Sin embargo, ayer los activistas de Igualdad Animal dijeron que no. Que ni esos. Lo pensaba porque, leyendo las ordenanzas municipales sobre animales dom\u00e9sticos, vi que un perro en Valencia tiene dificultades para ser [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[22,152],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/1796"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=1796"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/1796\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=1796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=1796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=1796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}