{"id":1835,"date":"2011-10-05T07:33:51","date_gmt":"2011-10-05T07:33:51","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/mariajosepou\/?p=1835"},"modified":"2011-10-05T07:33:51","modified_gmt":"2011-10-05T07:33:51","slug":"parches-para-bicis","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2011\/10\/05\/parches-para-bicis\/","title":{"rendered":"Parches para bicis"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2011\/10\/Valenbisi2.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-1836\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2011\/10\/Valenbisi2.jpg\" alt=\"\" width=\"300\" height=\"196\" \/><\/a>Varias veces he escrito que los ciclistas indocumentados que van por aceras, parques p\u00fablicos o pasos de peatones no habilitados son un peligro en aumento por la pasividad del Ayuntamiento.<\/p>\n<p style=\"text-align: justify\">Ahora la polic\u00eda da folletos advirtiendo de la prohibici\u00f3n de circular por las aceras o de sujetar la bici en cualquier tuber\u00eda del gas. Me alegro. Es un paso simb\u00f3lico pero necesario. Al menos corrige un d\u00e9ficit existente que bien podr\u00eda haberse paliado adjuntado a la tarjeta de Valenbisi una copia de la ordenanza municipal.<\/p>\n<p style=\"text-align: justify\">Lo digo porque los ciclistas &#8216;de toda la vida&#8217; suelen conocer y cumplir las normas pero muchos de los indocumentados son reci\u00e9n llegados que, aprovechando un servicio \u00fatil para la ciudad, se han lanzado a pedalear sin orden ni concierto.<\/p>\n<p style=\"text-align: justify\">Creo, sin embargo, que el folleto es caro y dudosamente \u00fatil. Una campa\u00f1a de sensibilizaci\u00f3n es imprescindible en una ciudad no acostumbrada. Eso incluye a peatones y conductores no solo de coches y motos sino tambi\u00e9n de autobuses.<\/p>\n<p style=\"text-align: justify\">La cuesti\u00f3n es que no basta con un folleto. El siguiente paso es la multa. No propugno una campa\u00f1a masiva pero en ocasiones me entretengo contando las infracciones que veo para saber cu\u00e1nto dinero pierde el Ayuntamiento, o sea, todos nosotros. La media est\u00e1 en 42 infracciones en una hora de paseo. Se lo brindo a nuestro Ilustr\u00edsimo Consistorio para que calcule cu\u00e1ntos carriles bici podr\u00edan financiarse con ello.<\/p>\n<p style=\"text-align: justify\">Carriles bici que, por cierto, deber\u00edan bajarse de las aceras tal y como han hecho en algunos tramos de Peris y Valero. En la calzada, pero separados del tr\u00e1fico para proteger al ciclista y con un ancho adecuado al paso de dos bicicletas.<\/p>\n<p style=\"text-align: justify\">Mantener los carriles en las aceras en multiplicar el problema y m\u00e1s cuando convergen con el peat\u00f3n en los pasos de cebra. Falta, pues, una visi\u00f3n de conjunto para abordar el problema de ra\u00edz y no a base de parches, sean folletos o m\u00e1s paradas de Valenbisi.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Varias veces he escrito que los ciclistas indocumentados que van por aceras, parques p\u00fablicos o pasos de peatones no habilitados son un peligro en aumento por la pasividad del Ayuntamiento. Ahora la polic\u00eda da folletos advirtiendo de la prohibici\u00f3n de circular por las aceras o de sujetar la bici en cualquier tuber\u00eda del gas. Me [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[29,152],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/1835"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=1835"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/1835\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=1835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=1835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=1835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}