{"id":1844,"date":"2011-10-08T07:28:35","date_gmt":"2011-10-08T07:28:35","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/mariajosepou\/?p=1844"},"modified":"2011-10-08T07:28:35","modified_gmt":"2011-10-08T07:28:35","slug":"urgencias-y-la-champions","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2011\/10\/08\/urgencias-y-la-champions\/","title":{"rendered":"Urgencias y la Champions"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2011\/10\/hospital-peset-urgencias.jpg\"><img loading=\"lazy\" class=\"alignleft size-full wp-image-1845\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2011\/10\/hospital-peset-urgencias.jpg\" alt=\"\" width=\"253\" height=\"190\" \/><\/a>Me lo hab\u00edan contado hace tiempo. Era como un chisme recurrente entre quienes conocen estos servicios: cuando hay partido, no hay aglomeraciones en urgencias. Sin embargo, a\u00fan teniendo visos de realidad, pensaba que era el t\u00edpico comentario que alguien lanza y se queda acu\u00f1ado para siempre. Por eso me extra\u00f1\u00f3 escuch\u00e1rselo al presidente de los empresarios, Vicente Boluda. Entiendo que tiene su l\u00f3gica pero de ah\u00ed a poner el caso de ejemplo para justificar el copago sanitario hay un abismo.<\/p>\n<p style=\"text-align: justify\">Cualquiera que haya ido a urgencias ha comprobado c\u00f3mo hay determinadas horas en las que baja la intensidad de los ingresos. Sin embargo, hay m\u00e1s momentos en que los servicios se saturan y no hay sitio ni para los enfermos que est\u00e1n esperando en un pasillo o junto a la m\u00e1quina de caf\u00e9, con sus v\u00f3mitos, sus dolores y su miedo a lo que les come por dentro. En una palabra, en los que una se pregunta si esa es la Sanidad que merece la dignidad de los enfermos.<\/p>\n<p style=\"text-align: justify\">Por eso no deber\u00edamos focalizar el inter\u00e9s en el mal uso de las urgencias sino en la raz\u00f3n de tal uso. Si a un ciudadano con un dolor terrible en la rodilla lo van citando para que le vea el m\u00e9dico de cabecera dentro de una semana; el especialista, dentro de seis; la radiograf\u00eda, en tres meses y el inicio del tratamiento, en medio a\u00f1o, es razonable que opte por ir a urgencias donde consigue en una noche que lo vean, le hagan la placa y le digan qu\u00e9 le pasa.<\/p>\n<p style=\"text-align: justify\">Y en la mayor\u00eda de los casos no hay una premeditaci\u00f3n censurable. Es puro hartazgo ante un sistema que no da cobertura a las necesidades. Es fruto de un cansancio o de una preocupaci\u00f3n que solo va en aumento conforme falla un diagn\u00f3stico, un tratamiento o simplemente una lista de espera que nunca acaba.<\/p>\n<p style=\"text-align: justify\">Ir a urgencias nunca es preferible. Que se lo digan a cualquiera que haya pasado por all\u00ed con algo serio. No es un capricho, pero el ciudadano sabe que, al menos, puede lograr una respuesta.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Me lo hab\u00edan contado hace tiempo. Era como un chisme recurrente entre quienes conocen estos servicios: cuando hay partido, no hay aglomeraciones en urgencias. Sin embargo, a\u00fan teniendo visos de realidad, pensaba que era el t\u00edpico comentario que alguien lanza y se queda acu\u00f1ado para siempre. Por eso me extra\u00f1\u00f3 escuch\u00e1rselo al presidente de los [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[54,65,156],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/1844"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=1844"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/1844\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=1844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=1844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=1844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}