{"id":1849,"date":"2011-10-09T08:27:32","date_gmt":"2011-10-09T08:27:32","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/mariajosepou\/?p=1849"},"modified":"2011-10-09T08:27:32","modified_gmt":"2011-10-09T08:27:32","slug":"mocador-per-a-plorar","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2011\/10\/09\/mocador-per-a-plorar\/","title":{"rendered":"Mocador per a plorar"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2011\/10\/299890114.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-1850\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2011\/10\/299890114.jpg\" alt=\"\" width=\"269\" height=\"300\" \/><\/a>Hoy m\u00e1s que nunca deber\u00edamos regalarnos todos una &#8216;mocador\u00e0&#8217;. No lo digo solo porque apetece sino porque el &#8216;mocador&#8217; enjugar\u00e1 las l\u00e1grimas de los contribuyentes que van a ser sangrados y los votantes que van a ser timados. A estos se les promete cambio. \u00bfA qu\u00e9? no se sabe, pero \u00abcambio\u00bb al fin y al cabo.<\/p>\n<p style=\"text-align: justify\">El mazap\u00e1n, dulz\u00f3n y vistoso en sus formas de frutas y verduras y de &#8216;piruleta&#8217; y &#8216;tronaor&#8217;, nos puede ayudar en el trance de ver a Rubalcaba sacando ideas descontextualizadas e inconexas por ganar un titular en el telediario.<\/p>\n<p style=\"text-align: justify\">La \u00faltima es de la de \u00abun pol\u00edtico, un sueldo\u00bb. Y lo dice ahora. \u00bfSe lo ha dicho a Gonz\u00e1lez que cobra del erario p\u00fablico y de la empresa privada? Ser\u00e1 que sigue siendo un solo sueldo. Un sueldo p\u00fablico. El otro depende de un consejo de administraci\u00f3n. Se mantiene, pues, en los equilibrios propios del candidato.<\/p>\n<p style=\"text-align: justify\">He de decir que a m\u00ed RbCb me empieza a dar l\u00e1stima. Lo veo ah\u00ed, hundido en las encuestas, cuando hace cuatro d\u00edas a\u00fan parec\u00eda remontar. Eso fue antes de que llegara el se\u00edsmo burs\u00e1til, la crisis del euro y los \u00faltimos varapalos financieros, la prima de riesgo y el primo griego poniendo en jaque todo el sistema. Incluido el camino de RbCb hacia el triunfo.<\/p>\n<p style=\"text-align: justify\">Ahora me da la sensaci\u00f3n de estar asistiendo al \u00faltimo espect\u00e1culo de un mago venido a menos a quien le fallan los trucos y solo sabe sacar pa\u00f1uelos o cartas marcadas de las mangas o de un bolsillo olvidado.<\/p>\n<p style=\"text-align: justify\">Enfrente un PP euf\u00f3rico que no va a consentir ni un solo palo en las ruedas hacia la Moncloa. Bien lo saben por estas tierras. Una esperanza de cambio de tendencia que es necesaria pero en la que hay dos planos: la ilusi\u00f3n de la transformaci\u00f3n deseada y la realidad de una legislatura dificil\u00edsima.<\/p>\n<p style=\"text-align: justify\">Entonces oiremos a los sindicatos, a los indignados y a los manifestantes de toda condici\u00f3n culpar a la derecha de todo. Habr\u00e1 que guardar el &#8216;mocador&#8217;. Por llorar o por pedir las dos orejas.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hoy m\u00e1s que nunca deber\u00edamos regalarnos todos una &#8216;mocador\u00e0&#8217;. No lo digo solo porque apetece sino porque el &#8216;mocador&#8217; enjugar\u00e1 las l\u00e1grimas de los contribuyentes que van a ser sangrados y los votantes que van a ser timados. A estos se les promete cambio. \u00bfA qu\u00e9? no se sabe, pero \u00abcambio\u00bb al fin y al [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[34,35,54,136,143,152,154],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/1849"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=1849"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/1849\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=1849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=1849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=1849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}