{"id":1892,"date":"2011-10-19T07:19:40","date_gmt":"2011-10-19T07:19:40","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/mariajosepou\/?p=1892"},"modified":"2011-10-19T07:19:40","modified_gmt":"2011-10-19T07:19:40","slug":"mil-por-uno","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2011\/10\/19\/mil-por-uno\/","title":{"rendered":"Mil por uno"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2011\/10\/LIBERADO-Shalit-telefono-israeli-EFE_CLAIMA20111018_0117_4.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-1893\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2011\/10\/LIBERADO-Shalit-telefono-israeli-EFE_CLAIMA20111018_0117_4.jpg\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/static-blogs.lasprovincias.es\/wp-content\/uploads\/sites\/4\/2011\/10\/LIBERADO-Shalit-telefono-israeli-EFE_CLAIMA20111018_0117_4.jpg 526w, https:\/\/static-blogs.lasprovincias.es\/wp-content\/uploads\/sites\/4\/2011\/10\/LIBERADO-Shalit-telefono-israeli-EFE_CLAIMA20111018_0117_4-300x169.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Shalit tiene 25 a\u00f1os. Schijveschurder ha cumplido 27. Shalit es soldado y ha permanecido secuestrado por Ham\u00e1s durante los \u00faltimos cinco a\u00f1os. Schijveschurder perdi\u00f3 a su familia en el atentado del restaurante Sbarro de Jerusal\u00e9n. Shalit habla de paz -\u00abojal\u00e1 este acuerdo lleve a la paz entre israel\u00edes y palestinos\u00bb-. Schijveschurder ha amenazado con vengar a sus padres y hermanos si se produce el canje anunciado, el de un israel\u00ed por m\u00e1s de mil palestinos.<\/p>\n<p style=\"text-align: justify\">Shalit est\u00e1 con vida y va a poder abrazar de nuevo a su familia. Schijveschurder nunca volver\u00e1 a encontrarse con los suyos. Ese es el motivo por el que podemos entender la posici\u00f3n de cada uno. A Shalit le han robado cinco a\u00f1os de vida pero a Schijveschurder le han arrancado la suya sin morir del todo.<\/p>\n<p style=\"text-align: justify\">Uno de los efectos perversos que ha tenido este conflicto y sobre todo la propaganda usada por Ham\u00e1s y jaleada en Occidente es el olvido de las v\u00edctimas. De Schijveschurder, por ejemplo.<\/p>\n<p style=\"text-align: justify\">Es asombroso que Espa\u00f1a, abierta en canal por la barbarie terrorista durante medio siglo, sea incapaz de tener presentes a tantas v\u00edctimas israel\u00edes. Nos falta tiempo para echar la culpa a su gobierno como si las v\u00edctimas de ETA lo fueran menos porque la Guardia Civil asfixia a la banda.<\/p>\n<p style=\"text-align: justify\">A\u00fan as\u00ed Israel ha liberado a presos condenados a cadena perpetua. Es cierto que ha valorado tanto la vida de uno de los suyos que la ha tasado en mil de los otros pero tambi\u00e9n el recuento de los muertos causados por \u00e9stos asciende a medio millar.<\/p>\n<p style=\"text-align: justify\">Es l\u00f3gico, pues, que los familiares de los asesinados se rebelen contra la decisi\u00f3n de Israel pero lo que sorprende es que, sabiendo el coste social y pol\u00edtico que esta decisi\u00f3n tendr\u00e1, no seamos capaces de reconocer lo que ha hecho Israel.<\/p>\n<p style=\"text-align: justify\">Es el problema de considerarle el malo de la pel\u00edcula que no solo es una mirada reduccionista y simple sino que supone una infamia hacia las v\u00edctimas de los terroristas liberados.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Shalit tiene 25 a\u00f1os. Schijveschurder ha cumplido 27. Shalit es soldado y ha permanecido secuestrado por Ham\u00e1s durante los \u00faltimos cinco a\u00f1os. Schijveschurder perdi\u00f3 a su familia en el atentado del restaurante Sbarro de Jerusal\u00e9n. Shalit habla de paz -\u00abojal\u00e1 este acuerdo lleve a la paz entre israel\u00edes y palestinos\u00bb-. Schijveschurder ha amenazado con vengar [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[98,169,180],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/1892"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=1892"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/1892\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=1892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=1892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=1892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}