{"id":1950,"date":"2011-11-01T09:06:08","date_gmt":"2011-11-01T09:06:08","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/mariajosepou\/?p=1950"},"modified":"2011-11-01T09:06:08","modified_gmt":"2011-11-01T09:06:08","slug":"santos-e-inocentes","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2011\/11\/01\/santos-e-inocentes\/","title":{"rendered":"Santos e inocentes"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2011\/11\/doom-miguelangel3.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-1951\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2011\/11\/doom-miguelangel3.jpg\" alt=\"\" width=\"300\" height=\"234\" \/><\/a>Desconozco si es mala idea presentar un programa electoral horas antes de que se celebre Halloween, como algunos criticaron ayer a Rajoy, pero de lo que no tengo duda es de que resulta curioso que la discusi\u00f3n sobre los programas electorales se produzca en la v\u00edspera de &#8216;Todos los santos&#8217;.<\/p>\n<p style=\"text-align: justify\">Es como si coincidiera con el 28 de diciembre, con la salvedad de que entonces todos har\u00edamos broma con la inocentada que nos gastan los partidos con sus programas. No es, pues, una inocentada pero s\u00ed un acto de fe.<\/p>\n<p style=\"text-align: justify\">Creer hoy en las promesas realizadas por unos y otros en v\u00edsperas de las elecciones es manifestar una fe profunda en un m\u00e1s all\u00e1 lleno de gozo para los justos y penas infinitas para los pecadores. Para algunos, los primeros ser\u00e1n los desahuciados del mundo y los segundos, los banqueros, inversores y especuladores de la peor cala\u00f1a y condici\u00f3n. Puede que usted y yo, por ejemplo, a poco que tengamos un fondo con los ahorros de toda una vida.<\/p>\n<p style=\"text-align: justify\">La festividad de hoy no es, como recuerda la Iglesia, una jornada dedicada a la muerte. \u00c9sa es la de ma\u00f1ana, el d\u00eda de \u00e1nimas. Hoy es para tener presentes a aquellos que, habiendo culminado el tr\u00e1nsito, ya est\u00e1n en la gloria eterna. Por eso me acongoja que nos presenten los programas electorales en una semana tan trascendente. Nunca mejor dicho.<\/p>\n<p style=\"text-align: justify\">\u00a1Unos santos somos los ciudadanos en estos momentos! No quiero pensar que inocentes y, por tanto, f\u00e1ciles de enga\u00f1ar, pero s\u00ed de una virtud elevada. Toda la que se necesita para aceptar que unos personajes que han demostrado su incapacidad para procurarnos unas condiciones de vida digna insistan en postularse de nuevo para el papel.<\/p>\n<p style=\"text-align: justify\">Somos almas en gracia limit\u00e1ndonos a enfadarnos sin cambiar la pancarta por la tarta. Y confiando, eso s\u00ed, en que existe una \u00abcomuni\u00f3n de los santos\u00bb, seg\u00fan la cual aquellos que ya viven en el para\u00edso eterno velar\u00e1n por quienes penamos todav\u00eda en este valle de l\u00e1grimas.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Desconozco si es mala idea presentar un programa electoral horas antes de que se celebre Halloween, como algunos criticaron ayer a Rajoy, pero de lo que no tengo duda es de que resulta curioso que la discusi\u00f3n sobre los programas electorales se produzca en la v\u00edspera de &#8216;Todos los santos&#8217;. Es como si coincidiera con [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[34,136,148],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/1950"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=1950"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/1950\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=1950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=1950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=1950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}