{"id":1953,"date":"2011-11-02T07:00:32","date_gmt":"2011-11-02T07:00:32","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/mariajosepou\/?p=1953"},"modified":"2011-11-02T07:00:32","modified_gmt":"2011-11-02T07:00:32","slug":"el-escozor-del-ganso","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2011\/11\/02\/el-escozor-del-ganso\/","title":{"rendered":"El escozor del ganso"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2011\/11\/sopa_de_ganso_m3_0_35_12_9202.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-1954\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2011\/11\/sopa_de_ganso_m3_0_35_12_9202.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a>Siempre he pensado que los pol\u00edticos tienen poco sentido del humor. Por eso no me extra\u00f1\u00f3 nada que se sintieran molestos cuando Blasco hizo proyectar la pel\u00edcula \u201cSopa de ganso\u201d. \u00bfC\u00f3mo se le ocurre poner la mirada de los hermanos Marx a un grupo de \u201cafectados\u201d por su cr\u00edtica c\u00e1ustica?<\/p>\n<p style=\"text-align: justify\">Cuentan las cr\u00f3nicas que el objetivo de quien seleccion\u00f3 la pel\u00edcula era animar a las tropas. En la \u00faltima ocasi\u00f3n electoral, lo hizo con \u201cInvictus\u201d, la historia de Mandela y el Mundial de Rugby, y este a\u00f1o pretend\u00eda conseguirlo con \u201cSopa de ganso\u201d.<\/p>\n<p style=\"text-align: justify\">La pel\u00edcula, vista desde quien contempla a Zapatero como el gran hacedor de cat\u00e1strofes puede resultar simp\u00e1tica pero en toda ella lo que se presenta es una mordaz y descarnada visi\u00f3n de la tarea pol\u00edtica. Es dif\u00edcil sustraerse a eso.<\/p>\n<p style=\"text-align: justify\">No hay m\u00e1s que recordar el momento en que le dicen al m\u00e1ximo dirigente (Groucho) que los trabajadores quieren horas m\u00e1s cortas y \u00e9l contesta: \u201cLes daremos horas m\u00e1s cortas. La hora del almuerzo durar\u00e1 veinte minutos\u201d. \u00bfQui\u00e9n no va a ver reflejada en esa frase la prestidigitaci\u00f3n de la realidad que hace el pol\u00edtico?<\/p>\n<p style=\"text-align: justify\">La pel\u00edcula \u2013la recomiendo- es ideal para los indignados pero no tanto para los pol\u00edticos en activo. Si la proyectaran en Sol, acabar\u00edan poniendo un altar a los \u201cotros Marx\u201d y sac\u00e1ndolos en procesi\u00f3n si eso se estilara por all\u00ed.<\/p>\n<p style=\"text-align: justify\">Vi\u00e9ndola es f\u00e1cil entender que se sintieran aludidos pero no como dicen algunos por ver reflejado el \u201ccaso valenciano\u201d sino por verse todos y cada uno. Sus comportamientos, sus atajos morales, sus soluciones improvisadas o su total irresponsabilidad sobre las consecuencias de sus acciones. Todo ello aparece en el film, de modo que resulta imposible animar as\u00ed a \u201clas tropas electorales\u201d.<\/p>\n<p style=\"text-align: justify\">Para conseguirlo deb\u00eda haber optado por \u201cGladiator\u201d o cualquier otra proyecci\u00f3n con tintes castrenses. Si lo que se pretende es arengar a los soldados, no se puede poner un espejo sino un relato \u00e9pico.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Siempre he pensado que los pol\u00edticos tienen poco sentido del humor. Por eso no me extra\u00f1\u00f3 nada que se sintieran molestos cuando Blasco hizo proyectar la pel\u00edcula \u201cSopa de ganso\u201d. \u00bfC\u00f3mo se le ocurre poner la mirada de los hermanos Marx a un grupo de \u201cafectados\u201d por su cr\u00edtica c\u00e1ustica? Cuentan las cr\u00f3nicas que el [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[43,136],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/1953"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=1953"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/1953\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=1953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=1953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=1953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}