{"id":3590,"date":"2012-01-03T16:35:27","date_gmt":"2012-01-03T16:35:27","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/mariajosepou\/?p=2159"},"modified":"2012-01-03T16:35:27","modified_gmt":"2012-01-03T16:35:27","slug":"el-bolsillo-del-abrigo","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/01\/03\/el-bolsillo-del-abrigo\/","title":{"rendered":"El bolsillo del abrigo"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/01\/fotonoticia_20120102092419_500.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-2160\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/01\/fotonoticia_20120102092419_500.jpg\" alt=\"\" width=\"300\" height=\"199\" \/><\/a>Estoy empezando a desarrollar cierto complejo de Banco Central. O de F\u00e1brica Nacional de Moneda y Timbre.<\/p>\n<p style=\"text-align: justify\">Lo digo porque parece que los ciudadanos seamos la bolsa del \u00faltimo recurso, como ese bolsillo que rebuscar en un abrigo del invierno pasado cuando nos falta suelto. All\u00ed siempre hay monedas y, con suerte, hasta encontramos alg\u00fan billete olvidado. Igual que el morral del ciudadano. Un sitio de donde sacar cuando todo falla.<\/p>\n<p style=\"text-align: justify\">Suben los precios del gas\u00f3leo profesional pero nos intentan tranquilizar diciendo que se congela la luz. \u00bfY qu\u00e9? Si se incrementa el coste del transporte ya podemos esperar un aumento generalizado de todos los precios, al fin y al cabo todo necesita ser llevado desde el punto de producci\u00f3n al de venta. Eso quiere decir que seremos los consumidores quienes en \u00faltima instancia pagaremos.<\/p>\n<p style=\"text-align: justify\">Lo mismo sucede con la propuesta de obligar a los bancos a pagar una tasa por tener cajeros autom\u00e1ticos en la calle. No hace falta ser un lince para adivinar qui\u00e9n terminar\u00e1 por financiar ese ingreso extra que obtendr\u00edan las arcas municipales. \u00bfDesde cu\u00e1ndo un banco sacrificar\u00eda una oportunidad de cobrar una comisi\u00f3n? Nada m\u00e1s l\u00f3gico que hacerlo en este caso cada vez que uno fuera a sacar dinero del cajero, \u00e9se que supondr\u00eda un gasto extra de aprobarse la iniciativa.<\/p>\n<p style=\"text-align: justify\">Pero el caso que m\u00e1s me ha enervado en estos d\u00edas es el de las ayudas a los bancos. No en s\u00ed la medida, que ya conocemos de ocasiones anteriores, sino la justificaci\u00f3n. Dice el ministro De Guindos que son necesarias para que vuelva a fluir el cr\u00e9dito. Ya s\u00e9 que el proceso no es autom\u00e1tico sino que esos 100.000 millones son para avalar las emisiones de bonos pero da la sensaci\u00f3n de estar dando dinero para que los bancos puedan darnos dinero a nosotros. La cosa estar\u00eda bien siempre que en el camino ese trueque no reportara beneficios a quien lo gestiona y s\u00ed a quien pone el dinero, o sea, los mismos de siempre.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Estoy empezando a desarrollar cierto complejo de Banco Central. O de F\u00e1brica Nacional de Moneda y Timbre. Lo digo porque parece que los ciudadanos seamos la bolsa del \u00faltimo recurso, como ese bolsillo que rebuscar en un abrigo del invierno pasado cuando nos falta suelto. All\u00ed siempre hay monedas y, con suerte, hasta encontramos alg\u00fan [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[26,53,54,132],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/3590"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=3590"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/3590\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=3590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=3590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=3590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}