{"id":3707,"date":"2012-01-16T09:04:25","date_gmt":"2012-01-16T09:04:25","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/mariajosepou\/?p=2208"},"modified":"2012-01-16T09:04:25","modified_gmt":"2012-01-16T09:04:25","slug":"mamon-a-bordo","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/01\/16\/mamon-a-bordo\/","title":{"rendered":"Mam\u00f3n a bordo"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/01\/P2012011615170331765181415.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-2209\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/01\/P2012011615170331765181415.jpg\" alt=\"\" width=\"300\" height=\"177\" \/><\/a>El comandante del Costa Concordia es un mam\u00f3n. No me lo tomen a mal. No lo digo con acritud ni tengo por costumbre usar palabras malsonantes o insultos en mis columnas, ya saben. Lo que quiero decir es que es, literalmente, un mam\u00f3n que, dicho en italiano, es un \u201cmammone\u201d.<\/p>\n<p style=\"text-align: justify\">Un \u201cmammone\u201d no es todo eso que decimos los espa\u00f1oles cuando le llamamos a uno con el apelativo, ni siquiera en modo cari\u00f1oso y con su correspondiente diminutivo \u201c\u00a1ay, mamoncete!\u201d.<\/p>\n<p style=\"text-align: justify\">En Italia se llama \u201cmammone\u201d a ese tipo adulto que no se separa de mam\u00e1, que siempre anda pegado a sus faldas y que es incapaz de ser aut\u00f3nomo, tomar decisiones por s\u00ed mismo o planificar su vida sin su benepl\u00e1cito.<\/p>\n<p style=\"text-align: justify\">Por eso supe que el comandante Schettino lo era \u2013si se confirma la hip\u00f3tesis de la huida- cuando me enter\u00e9 de lo sucedido mientras los pobres pasajeros intentaban sobrevivir.<\/p>\n<p style=\"text-align: justify\">Cuentan las cr\u00f3nicas m\u00e1s afiladas que, en lugar de ser el \u00faltimo en abandonar el barco como mandan los c\u00e1nones, la tradici\u00f3n y hasta la \u00e9pica, fue de los primeros en hacerlo. Pero lo peor no es eso sino que, ya en tierra, al parecer, tuvo tiempo de llamar a mam\u00e1 para decirle que no se preocupara, que aunque oyera noticias de un naufragio \u00e9l estaba bien y que hab\u00eda puesto a los pasajeros a salvo. Solo falt\u00f3 pedirle que le hiciera croquetas para cenar.<\/p>\n<p style=\"text-align: justify\">\u00bfQui\u00e9n puede pensar en llamar a su madre en esos momentos? No me refiero a las pobres victimas, muertas de miedo y de fr\u00edo, queriendo llamar a casa para tranquilizar a los familiares ante una eventual \u00faltima hora period\u00edstica. Lo digo por el responsable de un barco encallado del que todav\u00eda no hab\u00eda sido evacuado ni el pasaje ni la tripulaci\u00f3n.<\/p>\n<p style=\"text-align: justify\">\u00bfTanto temor reverencial le produc\u00eda su mam\u00e1 que se sent\u00eda obligado a llamar antes que nada, por miedo a la bronca posterior? Yo me temo que, vista la chapuza de tropezar con una \u201cchina\u201d en un mar tranquilo, la llamada era para decirle: \u201cmira, mam\u00e1, \u00a1sin manos!\u201d.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El comandante del Costa Concordia es un mam\u00f3n. No me lo tomen a mal. No lo digo con acritud ni tengo por costumbre usar palabras malsonantes o insultos en mis columnas, ya saben. Lo que quiero decir es que es, literalmente, un mam\u00f3n que, dicho en italiano, es un \u201cmammone\u201d. Un \u201cmammone\u201d no es todo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[173],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/3707"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=3707"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/3707\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=3707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=3707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=3707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}