{"id":3762,"date":"2012-01-23T08:00:42","date_gmt":"2012-01-23T08:00:42","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/mariajosepou\/?p=2229"},"modified":"2012-01-23T08:00:42","modified_gmt":"2012-01-23T08:00:42","slug":"insert-coin","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/01\/23\/insert-coin\/","title":{"rendered":"Insert coin"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/01\/72374485.jpg\"><img loading=\"lazy\" class=\"alignleft size-full wp-image-2230\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/01\/72374485.jpg\" alt=\"\" width=\"300\" height=\"156\" \/><\/a>Hay fuentes en las que la tradici\u00f3n manda lanzar una moneda a cambio de alg\u00fan beneficio. La m\u00e1s famosa es la Fontana de Trevi en la que el rito promete el regreso. Desde entonces, fuente que pisa el turista, c\u00e9ntimos que se deja. A veces, incluso, hay que a\u00f1adir agujeros, ruinas o cualquier resto donde un tarambana tira una moneda para que dos horas m\u00e1s tarde aquello est\u00e9 a rebosar.<\/p>\n<p style=\"text-align: justify\">Por eso no me extra\u00f1\u00f3 saber que la fuente del Palau de la M\u00fasica va a necesitar monedas para poner en marcha surtidores y m\u00fasica al comp\u00e1s. Pero no a la romana, tir\u00e1ndola de espaldas al pedir el deseo, sino a la valenciana, esto es, metiendo la moneda en la ranura.<\/p>\n<p style=\"text-align: justify\">Dicen los responsables municipales que ser\u00e1 como con las tracas que alguien quiere tirar, por ejemplo, en una boda. Previo paso por caja. En las fuentes del Palau habr\u00eda m\u00fasica si alguien la contratara.<\/p>\n<p style=\"text-align: justify\">Y yo ya lo estoy viendo. Imagino los valses de Strauss para unos novios que quieren el espect\u00e1culo en el v\u00eddeo de su boda pero tambi\u00e9n me temo que suene Lady Gaga porque un adolescente quiere decirle \u201cte quiero\u201d a su chica en un programa de televisi\u00f3n; el Chikilicuatre, para una cena de fin de curso o el \u201cI just wanna make love to you\u201d de Etta James, ahora que se ha ido, para una despedida de soltero.<\/p>\n<p style=\"text-align: justify\">Es m\u00e1s, quiz\u00e1s estemos a punto de inaugurar un nuevo m\u00e9todo recaudatorio basado en el \u201cinsert coin\u201d. No hay m\u00e1s que copiar a algunas zonas tur\u00edsticas, como esas iglesias oscuras en las que solo metiendo una moneda pueden verse los frescos de un gran pintor.<\/p>\n<p style=\"text-align: justify\">Cualquier d\u00eda tendremos eso en las farolas: si quiere tener luz para llegar a casa, 20 c\u00e9ntimos. Si la quiere con sem\u00e1foros encendidos, 50. Si quiere papeleras abiertas, 60 c\u00e9ntimos; si la quiere con bolsa para perros, 1 euro. Si quiere ver las Torres de Serrano iluminadas para la foto, 2 euros y si quiere escuchar las campanas del Micalet, meta un billete de 10, no me sea r\u00e1cano.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hay fuentes en las que la tradici\u00f3n manda lanzar una moneda a cambio de alg\u00fan beneficio. La m\u00e1s famosa es la Fontana de Trevi en la que el rito promete el regreso. Desde entonces, fuente que pisa el turista, c\u00e9ntimos que se deja. A veces, incluso, hay que a\u00f1adir agujeros, ruinas o cualquier resto donde [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[54,152],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/3762"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=3762"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/3762\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=3762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=3762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=3762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}