{"id":3936,"date":"2012-03-06T15:11:27","date_gmt":"2012-03-06T15:11:27","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=3936"},"modified":"2012-03-06T15:11:27","modified_gmt":"2012-03-06T15:11:27","slug":"valenciano-no-corrupto","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/03\/06\/valenciano-no-corrupto\/","title":{"rendered":"Valenciano, no corrupto"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/03\/images1.jpeg\"><img loading=\"lazy\" class=\"alignleft size-full wp-image-3937\" title=\"images\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/03\/images1.jpeg\" alt=\"\" width=\"275\" height=\"183\" \/><\/a>Valencia exist\u00eda antes de Germana de Foix y, aunque malherida, continu\u00f3 tras ella. Viv\u00eda antes de Felipe V y, aunque maltrecha, volvi\u00f3 a levantar cabeza. Lleg\u00f3 entera a ser capital de la Rep\u00fablica, sobrevivi\u00f3 a la sangr\u00eda de una guerra entre hermanos y resisti\u00f3 a una postguerra feroz. Valencia se ha visto en trances peores y ha sabido salir de ellos. Sobre todo, porque no la han sacado sus dirigentes. Ha salido por sus propios medios.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, cada tiempo y cada lucha han dejado su huella. La p\u00e9rdida del valenciano como lengua de prestigio; la tiran\u00eda; la amputaci\u00f3n de una parte de s\u00ed misma con la expulsi\u00f3n de jud\u00edos y moriscos o la eliminaci\u00f3n de los fueros propios. Ha habido \u00e9pocas de dolor, crisis, represiones, abusos y poblaciones asfixiadas por unos dirigentes que se aprovecharon de la buena fe, del car\u00e1cter no belicoso de sus gentes o de la lealtad al poder por convicci\u00f3n o por miedo.<\/p>\n<p style=\"text-align: justify;\">Por eso no deber\u00edamos mantener como cierta esa relaci\u00f3n falaz entre la cr\u00edtica a los errores pol\u00edticos y el ataque a un pueblo, lo diga el Conde-Duque de Olivares o el ministro Garc\u00eda-Margallo. No es a los valencianos a quienes se nos insulta hablando de corruptelas. Es a los corruptos. No es a los valencianos a quienes se nos descalifica por obras fara\u00f3nicas; es a quienes las encargaron y pagaron.<\/p>\n<p style=\"text-align: justify;\">Ahora bien, sus corruptelas e iniciativas megal\u00f3manas las hicieron y financiaron en nuestro nombre, por nuestro bien (sic) y a nuestro cargo. Y ah\u00ed, s\u00ed, tenemos un mea culpa que entonar. Y un error hist\u00f3rico que enmendar.<\/p>\n<p style=\"text-align: justify;\">Los \u201cagermanats\u201d no pod\u00edan sino dejarse la vida, como lo hicieron. Ellos luchaban contra fusiles de asalto y ten\u00edan las de perder, pero los valencianos de hoy, no. Hoy contamos con la libertad de escoger y juzgar la gesti\u00f3n de nuestros mandatarios. Podemos decir en alto que da igual si nacieron a orillas del Turia o del Rhin. Lo vergonzante no es ser valenciano sino corrupto.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Valencia exist\u00eda antes de Germana de Foix y, aunque malherida, continu\u00f3 tras ella. Viv\u00eda antes de Felipe V y, aunque maltrecha, volvi\u00f3 a levantar cabeza. Lleg\u00f3 entera a ser capital de la Rep\u00fablica, sobrevivi\u00f3 a la sangr\u00eda de una guerra entre hermanos y resisti\u00f3 a una postguerra feroz. Valencia se ha visto en trances peores [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[53,136],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/3936"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=3936"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/3936\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=3936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=3936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=3936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}