{"id":3953,"date":"2012-03-12T07:13:33","date_gmt":"2012-03-12T07:13:33","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=3953"},"modified":"2012-03-12T07:13:33","modified_gmt":"2012-03-12T07:13:33","slug":"ninots-por-encargo","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/03\/12\/ninots-por-encargo\/","title":{"rendered":"Ninots por encargo"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/03\/images5.jpeg\"><img loading=\"lazy\" class=\"alignleft size-full wp-image-3954\" title=\"images\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/03\/images5.jpeg\" alt=\"\" width=\"259\" height=\"194\" \/><\/a>Entiendo que ante la escasez de recursos es necesario agarrarse a un cheque ardiendo pero hay patrocinios en Fallas que me incomodan. Una cosa es ver una valla con publicidad rodeando un monumento y otra, que la luz de la calle no evoque el nombre de la comisi\u00f3n como \u201cLa Falla de Pere\u201d o \u201cAlmirante\u201d sino una marca publicitaria.<\/p>\n<p style=\"text-align: justify;\">Esa molestia a\u00fan me enfada m\u00e1s cuando se presenta como novedad algo que solo intenta vendernos un producto. Lo digo por dos ideas interesantes que se acaban de dar a conocer: el perfume de p\u00f3lvora y la falla tecnol\u00f3gica.<\/p>\n<p style=\"text-align: justify;\">Con los dos piqu\u00e9 y quiz\u00e1s sea eso lo que menos me gust\u00f3: la sensaci\u00f3n de timo. Y en realidad no puede decirse que sea un enga\u00f1o porque ambas existieron, pero no como lo que parec\u00edan ser sino como soporte de una treta comercial. Ah\u00ed reside el problema.<\/p>\n<p style=\"text-align: justify;\">A eso se une que los medios de comunicaci\u00f3n lo presentan como novedad y obvian el anuncio que subyace de modo que solo al final, cuando una ya se ha encandilado con la propuesta, se encuentra con que el objetivo era venderle algo que ni siquiera tiene que ver con la ocurrencia.<\/p>\n<p style=\"text-align: justify;\">Eso me pas\u00f3 con el Masclet n.5. No s\u00e9 si me alguna vez me hubiera acostado, como dicen que hac\u00eda Marilyn, solo con unas gotitas de ese perfume pero reconozco que el mensaje hubiera sido evidente para cualquiera. En lugar de ir pidiendo guerra, hubiera pedido una masclet\u00e0 completa, con fuego a\u00e9reo y todo. Ellos quiz\u00e1s me hubieran calificado de \u201cexplosiva\u201d pero ellas, sin duda, hubieran optado por \u201cpetarda\u201d. Y seguramente hubieran acertado. Lo que me fastidi\u00f3 fue saber que el invento no era m\u00e1s que el reclamo de una cerveza.<\/p>\n<p style=\"text-align: justify;\">Lo mismo me pas\u00f3 con la falla tecnol\u00f3gica, propuesta apetecible por lo limpia, exportable y ecol\u00f3gica, que no era m\u00e1s que la forma de presentar un coche.<\/p>\n<p style=\"text-align: justify;\">Cosas de la crisis, supongo. Espero con ansia el d\u00eda que nos dejen patrocinar un ninot por encargo. Para quemar con ganas, por supuesto.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Entiendo que ante la escasez de recursos es necesario agarrarse a un cheque ardiendo pero hay patrocinios en Fallas que me incomodan. Una cosa es ver una valla con publicidad rodeando un monumento y otra, que la luz de la calle no evoque el nombre de la comisi\u00f3n como \u201cLa Falla de Pere\u201d o \u201cAlmirante\u201d [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[75,141],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/3953"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=3953"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/3953\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=3953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=3953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=3953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}