{"id":3966,"date":"2012-03-16T09:06:35","date_gmt":"2012-03-16T09:06:35","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=3966"},"modified":"2012-03-16T09:06:35","modified_gmt":"2012-03-16T09:06:35","slug":"fracaso-escolar-2-0","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/03\/16\/fracaso-escolar-2-0\/","title":{"rendered":"Fracaso escolar 2.0"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/03\/images-1.jpeg\"><img loading=\"lazy\" class=\"alignleft size-full wp-image-3967\" title=\"images-1\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/03\/images-1.jpeg\" alt=\"\" width=\"262\" height=\"193\" \/><\/a>\u00bfEs necesario que alguien le diga a usted que la pieza clave de la ense\u00f1anza es el profesor? \u00bfA que no? Pues ayer tuvimos que escucharlo durante la presentaci\u00f3n del \u201cInforme de Tecnolog\u00eda Educativa 2011\u201d.<\/p>\n<p style=\"text-align: justify;\">En \u00e9l se hace un diagn\u00f3stico cr\u00edtico sobre la introducci\u00f3n indiscriminada de la tecnolog\u00eda en las aulas hasta el punto de calificar de \u201cextremadamente imprudente\u201d el proyecto Escuela 2.0 del que tanto presumi\u00f3 el anterior gobierno. Seg\u00fan los analistas, el uso de ordenadores en las clases pudiera haber bajado el rendimiento escolar en Espa\u00f1a.<\/p>\n<p style=\"text-align: justify;\">\u00bfSignifica eso que debemos quedarnos en la tiza y la pizarra? Ni mucho menos.<\/p>\n<p style=\"text-align: justify;\">Si el profesor sabe qu\u00e9 es alentar en el descubrimiento del saber, lo hace con tiza, con meg\u00e1fono, con m\u00edmica o con iPad. El problema es querer encubrir la falta de dedicaci\u00f3n, de preparaci\u00f3n, de inter\u00e9s o de medios con una pizarra digital o con una p\u00e1gina web. Y no solo es problema del docente sino tambi\u00e9n de centros de ense\u00f1anza y autoridades educativas.<\/p>\n<p style=\"text-align: justify;\">A m\u00ed no me tienen que convencer. Lo veo a diario en las clases. Est\u00e1n con su port\u00e1til y mientras unos toman nota y otros consultan la portada de prensa que comentas, algunos sonr\u00eden entre dientes y escriben cada diez segundos. \u00bfToman apuntes? \u00bfUsted cree que la ret\u00f3rica de Arist\u00f3teles provoca caras mo\u00f1as, sonrisitas, codazos al vecino y rubor? \u00bfNo ser\u00e1 que andan chateando con la chiquita que les gusta y a la que quieren llevarse de botell\u00f3n?<\/p>\n<p style=\"text-align: justify;\">Eso no impide que una servidora, al tiempo que cuestiona el uso de los port\u00e1tiles, est\u00e9 preparando materiales para clase con formato eBook; haya iniciado una web en Facebook para montar debates con los alumnos o les d\u00e9 la direcci\u00f3n de Twitter para comentar noticias. La cuesti\u00f3n es saber qu\u00e9 deben conocer los chavales y c\u00f3mo hacer que lo aprendan de la forma m\u00e1s eficaz. Lo dem\u00e1s es pura pol\u00edtica o \u201cperroflautismo\u201d pedag\u00f3gico, que haberlo, haylo. Y con rastas neuronales.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00bfEs necesario que alguien le diga a usted que la pieza clave de la ense\u00f1anza es el profesor? \u00bfA que no? Pues ayer tuvimos que escucharlo durante la presentaci\u00f3n del \u201cInforme de Tecnolog\u00eda Educativa 2011\u201d. En \u00e9l se hace un diagn\u00f3stico cr\u00edtico sobre la introducci\u00f3n indiscriminada de la tecnolog\u00eda en las aulas hasta el punto [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[66,136,166],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/3966"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=3966"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/3966\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=3966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=3966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=3966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}