{"id":4003,"date":"2012-03-28T06:22:04","date_gmt":"2012-03-28T04:22:04","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=4003"},"modified":"2012-03-28T06:22:04","modified_gmt":"2012-03-28T04:22:04","slug":"el-bibliotecario-y-el-te","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/03\/28\/el-bibliotecario-y-el-te\/","title":{"rendered":"El bibliotecario y el t\u00e9"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/03\/resizer-1.php_.jpeg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-4004\" title=\"resizer-1.php\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/03\/resizer-1.php_.jpg\" alt=\"\" width=\"300\" height=\"187\" \/><\/a>Algunos vecinos del llamado \u201cbibliotecario de Al Qaeda\u201d dicen que no lo conoc\u00edan. Otros, en cambio, que tanto la mujer como la hija eran encantadoras. E incluso los hay que calificaron a todos los miembros de la familia de \u201cnormales\u201d. Es un alivio. Solo faltaba que adem\u00e1s de presunto terrorista tuviera dos cuernos, colmillos a lo Crep\u00fasculo y una capa de la invisibilidad como Harry Potter. Si as\u00ed hubiera sido, no hubiera podido realizar su trabajo de propaganda. Pero no por ser terrorista, sino \u201crarito\u201d. Y eso, como sabemos, es lo peor que te puede considerar un vecino.<\/p>\n<p style=\"text-align: justify;\">Lo que m\u00e1s me llam\u00f3 la atenci\u00f3n fue otra cosa que indica una visi\u00f3n estereotipada de nuestros compatriotas \u201cdiferentes\u201d. Dec\u00eda alguno que \u201cno ten\u00edan costumbres \u00e1rabes\u201d. Y yo me pregunto cu\u00e1les son esas costumbres tan peligrosas.<\/p>\n<p style=\"text-align: justify;\">Que yo sepa, la hospitalidad es muy propia del mundo \u00e1rabe hasta el punto de que no es extra\u00f1o ser invitado a tomar un t\u00e9 en una tienda de alfombras en Turqu\u00eda. Todo por el Business.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, si los vecinos del presunto terrorista hubieran tomado t\u00e9 en su casa nunca hubieran considerado ese gesto como demostraci\u00f3n de su condici\u00f3n de asesino peligroso ni de su pertenencia a Al Qaeda. Simplemente hubieran pensado que su nuevo vecino era un tipo amable y con ganas de llevarse bien con los dem\u00e1s. Quiz\u00e1s hasta hubieran confundido ese detalle con la costumbre estadounidense de presentarse al vecindario y \u00e9ste al nuevo habitante del barrio con una tarta de manzana, unas magdalenas o unas pastas.<\/p>\n<p style=\"text-align: justify;\">La cuesti\u00f3n es que ese t\u00e9 hubiera respondido a una costumbre \u00e1rabe, pero no es eso a lo que se refer\u00eda el testigo. Seguramente se sorprend\u00eda con que el extremista viviera como un occidental. Pero, si hubiera llevado barba y hubiera rezado en la acera hacia La Meca \u00bfhubiera sido considerado un potencial yihadista? No s\u00e9 qu\u00e9 es m\u00e1s peligroso, pues, si el terrorista o el que los ve por todas partes.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Algunos vecinos del llamado \u201cbibliotecario de Al Qaeda\u201d dicen que no lo conoc\u00edan. Otros, en cambio, que tanto la mujer como la hija eran encantadoras. E incluso los hay que calificaron a todos los miembros de la familia de \u201cnormales\u201d. Es un alivio. Solo faltaba que adem\u00e1s de presunto terrorista tuviera dos cuernos, colmillos a [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[148,169],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4003"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=4003"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4003\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=4003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=4003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=4003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}