{"id":4059,"date":"2012-04-18T08:00:44","date_gmt":"2012-04-18T06:00:44","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=4059"},"modified":"2012-04-18T08:00:44","modified_gmt":"2012-04-18T06:00:44","slug":"bienvenidos-a-patagonia-o-el-reportaje-que-tve-no-emitio","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/04\/18\/bienvenidos-a-patagonia-o-el-reportaje-que-tve-no-emitio\/","title":{"rendered":"Bienvenidos a Patagonia o el reportaje que TVE no emiti\u00f3"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/04\/images8.jpeg\"><img loading=\"lazy\" class=\"size-full wp-image-4060 alignleft\" title=\"images\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/04\/images8.jpeg\" alt=\"\" width=\"285\" height=\"177\" \/><\/a>Anoche, TVE deb\u00eda haber emitido (en redifusi\u00f3n) un programa de &#8220;Espa\u00f1oles por el mundo&#8221; que los situaba -v\u00e1lgame Dios- en la Patagonia argentina y chilena. Eso no es punter\u00eda, eso es pegarse un tiro en la tercera falange del dedo me\u00f1ique, que dir\u00eda el ministro Margallo. \u00bfY qu\u00e9 hacer?, se plantearon los responsables.<\/p>\n<p style=\"text-align: justify;\">Si lo emit\u00edan, qui\u00e9n sabe si K hubiera decidido por su cuenta y riesgo expropiar a esos espa\u00f1olitos que andan por los hielos australes. Si no lo hac\u00edan, tendr\u00edan que explicar muy bien su posici\u00f3n para no empeorar a\u00fan m\u00e1s las cosas.<\/p>\n<p style=\"text-align: justify;\">Al final justificaron el cambio por &#8220;razones de programaci\u00f3n&#8221; que es a la televisi\u00f3n lo que &#8220;un virus&#8221; a los diagn\u00f3sticos m\u00e9dicos, es decir, una soluci\u00f3n \u00f3ptima para todo cuando no se sabe muy bien qu\u00e9 decir. Como &#8220;el f\u00fatbol es as\u00ed&#8221; pero con menos fe en el Alt\u00edsimo.<\/p>\n<p style=\"text-align: justify;\">La soluci\u00f3n no parece la mejor, aunque tampoco la peor. A todas luces parec\u00eda inoportuna la emisi\u00f3n porque a m\u00e1s de un argentino le hubieran entrado ganas de a\u00f1adir en el t\u00edtulo &#8220;espa\u00f1oles <span style=\"color: #ff0000;\">imperialistas<\/span> por el mundo&#8221; y donde dice &#8220;imperialistas&#8221;, pongan ustedes lo que quieran. Pero no haberlo emitido puede interpretarse como un desplante hacia un pa\u00eds que, como ha reiterado mil veces en estas horas el ministro Soria, es amigo y no se debe meter en el mismo saco que sus dirigentes.<\/p>\n<p style=\"text-align: justify;\">En cualquier caso, era un gesto simb\u00f3lico nada m\u00e1s porque el reportaje ya se conoc\u00eda y adem\u00e1s est\u00e1 <a href=\"http:\/\/www.rtve.es\/alacarta\/videos\/television\/espanoles-mundo--patagonia\/645394\/\" target=\"_blank\" rel=\"external nofollow\">disponible<\/a> en la web de RTVE<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Anoche, TVE deb\u00eda haber emitido (en redifusi\u00f3n) un programa de &#8220;Espa\u00f1oles por el mundo&#8221; que los situaba -v\u00e1lgame Dios- en la Patagonia argentina y chilena. Eso no es punter\u00eda, eso es pegarse un tiro en la tercera falange del dedo me\u00f1ique, que dir\u00eda el ministro Margallo. \u00bfY qu\u00e9 hacer?, se plantearon los responsables. Si lo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[168],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4059"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=4059"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4059\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=4059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=4059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=4059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}