{"id":4086,"date":"2012-04-23T18:44:06","date_gmt":"2012-04-23T16:44:06","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=4086"},"modified":"2012-04-23T18:44:06","modified_gmt":"2012-04-23T16:44:06","slug":"que-libro-lee","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/04\/23\/que-libro-lee\/","title":{"rendered":"\u00bfQu\u00e9 libro lee?"},"content":{"rendered":"<p><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/04\/suiza-feria-libro-feria-del-libro-de-basilea.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-4087\" title=\"suiza-feria-libro-feria-del-libro-de-basilea-01$599x0\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/04\/suiza-feria-libro-feria-del-libro-de-basilea.jpg\" alt=\"\" width=\"300\" height=\"199\" \/><\/a>Es una pena que los periodistas dejen para un d\u00eda como hoy la pregunta \u00bfqu\u00e9 libro est\u00e1 leyendo? En el D\u00eda del Libro inquieren a pol\u00edticos, l\u00edderes sociales o intelectuales sobre el contenido de su mesita de noche, pero deber\u00edan hacerlo en todo momento, sobre todo, en momentos inesperados.<\/p>\n<p>Preguntarlo en un 23 de abril es demasiado previsible. As\u00ed, es posible que no pille desprevenidos a los jefes de gabinete de los pol\u00edticos, que les preparan una relaci\u00f3n de libros-s\u00edmbolo. Porque existen. Igual que hay quien usa el coche como signo de riqueza, poder o seducci\u00f3n, los pol\u00edticos escogen el \u201clibro preferido\u201d como resumen de su filosof\u00eda, de sus intenciones o de su reproche al l\u00edder. Son los libros-mensaje.<\/p>\n<p>No hay m\u00e1s que recordar a Hugo Ch\u00e1vez comprando en la Casa del Libro de Madrid el de Galeano \u201cLas venas abiertas de Am\u00e9rica Latina\u201d o a Zapatero, en la Feria del Libro, llev\u00e1ndose \u201cEl soldado y la ni\u00f1a\u201d, un alegato contra las guerras de Jordi Sierra.<\/p>\n<p>Al parecer, no pueden leer cosas normales e incluso vulgares. No pueden leerse una novela de aeropuerto ni una comedia ligera o un best-seller sin sustancia pero con mucha acci\u00f3n. No. Tiene que ser un libro capaz de resumir aquello que les preocupa en el momento.<\/p>\n<p>Y ah\u00ed es donde reside el peligro. Los pol\u00edticos suelen vivir en el corto plazo y, consecuentemente, tambi\u00e9n leen con la mirada miope. Eso significa que suelen quedarse en el tema del momento, el personaje del mes o la preocupaci\u00f3n m\u00e1s reciente en lugar de hacer lo mejor de la lectura: adentrarse en el pasado y en el presente desde la profundidad de los grandes asuntos.<\/p>\n<p>Siempre espero escuchar a un pol\u00edtico decir que \u201crelee\u201d un cl\u00e1sico. \u00bfPor qu\u00e9 no? A partir de determinada edad, es m\u00e1s placentero releer que leer, sobre todo, en tiempos de crisis que obligan a mirar lo mismo de nuevo, es decir, con una mirada nueva. Dicho esto, les dejo y vuelvo sobre Homero. Es lo m\u00ednimo.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Es una pena que los periodistas dejen para un d\u00eda como hoy la pregunta \u00bfqu\u00e9 libro est\u00e1 leyendo? En el D\u00eda del Libro inquieren a pol\u00edticos, l\u00edderes sociales o intelectuales sobre el contenido de su mesita de noche, pero deber\u00edan hacerlo en todo momento, sobre todo, en momentos inesperados. Preguntarlo en un 23 de abril [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[56,129,136,149],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4086"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=4086"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4086\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=4086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=4086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=4086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}