{"id":4158,"date":"2012-05-15T21:00:11","date_gmt":"2012-05-15T19:00:11","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=4158"},"modified":"2012-05-15T21:00:11","modified_gmt":"2012-05-15T19:00:11","slug":"fantasias-medicas","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/05\/15\/fantasias-medicas\/","title":{"rendered":"Fantas\u00edas m\u00e9dicas"},"content":{"rendered":"<p><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/05\/cavadas2-253x190.jpg\"><img loading=\"lazy\" class=\"size-full wp-image-4159 alignleft\" title=\"cavadas2--253x190\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/05\/cavadas2.jpg\" alt=\"\" width=\"253\" height=\"190\" \/><\/a>La interpretaci\u00f3n de un escrito es libre pero la rapidez con la que circula hoy la respuesta a lo publicado hace que se potencien reacciones desafortunadas. Hace unos d\u00edas, una servidora lo vivi\u00f3 en primera persona.<\/p>\n<p>Despu\u00e9s de criticar duramente a \u201clos bankeros\u201d consider\u00e1ndolos usureros de la peor cala\u00f1a a ra\u00edz del caso Bankia, un lector me escribi\u00f3 airado porque, a su entender, despreciaba a los pobres. Precisamente hac\u00eda lo contrario, es decir, reivindicaba que los pobres, aunque no tuvieran el peso de los grandes bancos en la econom\u00eda, deb\u00edan ser rescatados y ayudados en la crisis. Al parecer no qued\u00f3 suficientemente claro y me da la sensaci\u00f3n de que es lo que le ha sucedido a Cavadas.<\/p>\n<p>Por mucho que leo sus declaraciones no encuentro el desatino que le achacan. Es verdad que alert\u00f3 sobre una imagen distorsionada de lo que significa ser m\u00e9dico: \u201cNo creo en la vocaci\u00f3n. Dudo mucho que un ni\u00f1o entienda qu\u00e9 es ser m\u00e9dico. Te puede gustar llevar bata blanca o que creas que vas a ganar mucha pasta o que te tirar\u00e1s a la enfermera, pero conocer profundamente la profesi\u00f3n es imposible\u201d.<\/p>\n<p><img loading=\"lazy\" class=\"alignright size-full wp-image-4160\" title=\"images-1\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/05\/images-14.jpeg\" alt=\"\" width=\"202\" height=\"152\" \/><\/p>\n<p>De esas frases han extra\u00eddo una visi\u00f3n despreciativa hacia los profesionales de la enfermer\u00eda y, sin embargo, yo creo que Cavadas censura un estereotipo que nada tiene que ver con la realidad. Lo mismo les sucede a los que estudian para pilotos pensando que su vida ser\u00e1 liarse cada d\u00eda con una azafata distinta. Pensar eso es una estupidez pero en los inicios de una carrera puede haber deformaciones de la realidad por efecto del cine, de la televisi\u00f3n o de leyendas urbanas sin ning\u00fan fundamento.<\/p>\n<p>Tambi\u00e9n ocurre con los periodistas. Los hay que en primero de carrera quieren recorrer el mundo de aventura en aventura o hacerse famosos en la tele. Los que conocemos esto sabemos lo que tiene de verdad el mito. Como les ocurre a los enfermeros y espero que tambi\u00e9n a Cavadas, aunque una aclaraci\u00f3n no estar\u00eda de m\u00e1s.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La interpretaci\u00f3n de un escrito es libre pero la rapidez con la que circula hoy la respuesta a lo publicado hace que se potencien reacciones desafortunadas. Hace unos d\u00edas, una servidora lo vivi\u00f3 en primera persona. Despu\u00e9s de criticar duramente a \u201clos bankeros\u201d consider\u00e1ndolos usureros de la peor cala\u00f1a a ra\u00edz del caso Bankia, un [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[156,171],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4158"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=4158"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4158\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=4158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=4158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=4158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}