{"id":4278,"date":"2012-06-14T22:44:23","date_gmt":"2012-06-14T20:44:23","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=4278"},"modified":"2012-06-14T22:44:23","modified_gmt":"2012-06-14T20:44:23","slug":"las-mujeres-de-hollande","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/06\/14\/las-mujeres-de-hollande\/","title":{"rendered":"Las mujeres de Hollande"},"content":{"rendered":"<p><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/06\/images-17.jpeg\"><img loading=\"lazy\" class=\"alignleft size-full wp-image-4280\" title=\"images-1\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/06\/images-17.jpeg\" alt=\"\" width=\"275\" height=\"183\" \/><\/a>Pocos gestos de machismo me fastidian tanto como el de una mujer hacia otra. Y a veces ni siquiera se da cuenta.<\/p>\n<p>Pienso por ejemplo en quienes defienden que las mujeres conducimos peor que los hombres. El dato se desmiente con las p\u00f3lizas de las aseguradoras. Si \u00e9sas, que pierden dinero con el mal conductor, hacen ofertas cuando se trata de una mujer, no puede afirmarse que su conducci\u00f3n sea descuidada y peligrosa. En general. Tambi\u00e9n las hay torpes, como hombres que parecen haber obtenido el carnet en la t\u00f3mbola.<\/p>\n<p>Por mi parte, si no puedo cambiarla, me aprovecho de la \u201cmentalidad machista\u201d. Es algo que suele hacer re\u00edr a mis amigas cuando hago una tropel\u00eda a sabiendas pero con cara de mujer-in\u00fatil al volante. Si de todos modos lo van a atribuir a mi g\u00e9nero y no a mis capacidades, \u00bfpor qu\u00e9 no hacer lo que me d\u00e9 la gana?<\/p>\n<p>Lo resumo en las rotondas cuando digo \u201cme cruzo, me cruzo, porque soy mujer y no me entero\u201d mientras cambio de carril, con gesto de \u201cups, por qu\u00e9 pitan si yo voy bien\u201d, y acabo donde me interesa. Con absoluta consciencia pero con gesto de despiste. Al fin y al cabo muchos hombres lo hacen pensando \u201cla calzada es m\u00eda que soy un machote\u201d. Ellos lo hacen con chuler\u00eda; yo, con falsa inocencia.<\/p>\n<p>Digo todo esto por el revuelo que se ha montado en Francia al apoyar la pareja actual de Hollande al candidato contrario a la ex del presidente franc\u00e9s mientras \u00e9ste, sin embargo, la avala.<a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/06\/156547-12_06_2012_18_03_41_237370955.jpg\"><img loading=\"lazy\" class=\"alignright size-medium wp-image-4279\" title=\"156547-12_06_2012_18_03_41_237370955\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/06\/156547-12_06_2012_18_03_41_237370955.jpg\" alt=\"\" width=\"300\" height=\"264\" srcset=\"https:\/\/static-blogs.lasprovincias.es\/wp-content\/uploads\/sites\/4\/2012\/06\/156547-12_06_2012_18_03_41_237370955.jpg 367w, https:\/\/static-blogs.lasprovincias.es\/wp-content\/uploads\/sites\/4\/2012\/06\/156547-12_06_2012_18_03_41_237370955-300x264.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Es bueno que tenga libertad de criterio para apoyar a quien le parezca aunque no coincida con el presidente. Lo contrario ser\u00eda frustrante.<\/p>\n<p>Sin embargo, corre el riesgo de ser interpretado todo como un despecho contra la ex de su pareja. O sea, en clave machista, dando por hecho que una mujer se deja llevar siempre por sus pasiones y no por su cerebro.<\/p>\n<p>Su gesto, libre y noble, puede llevar a equ\u00edvoco que favorezca tesis sexistas. Y una comunicadora como ella deber\u00eda haberlo calculado.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Pocos gestos de machismo me fastidian tanto como el de una mujer hacia otra. Y a veces ni siquiera se da cuenta. Pienso por ejemplo en quienes defienden que las mujeres conducimos peor que los hombres. El dato se desmiente con las p\u00f3lizas de las aseguradoras. Si \u00e9sas, que pierden dinero con el mal conductor, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[116,136],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4278"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=4278"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4278\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=4278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=4278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=4278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}