{"id":4325,"date":"2012-06-28T23:08:51","date_gmt":"2012-06-28T21:08:51","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=4325"},"modified":"2012-06-28T23:08:51","modified_gmt":"2012-06-28T21:08:51","slug":"un-pulpo-y-una-nutria","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/06\/28\/un-pulpo-y-una-nutria\/","title":{"rendered":"Un pulpo y una nutria"},"content":{"rendered":"<p><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/06\/181476_389341564446562_1564396025_n.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-4326\" title=\"181476_389341564446562_1564396025_n\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/06\/181476_389341564446562_1564396025_n.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/static-blogs.lasprovincias.es\/wp-content\/uploads\/sites\/4\/2012\/06\/181476_389341564446562_1564396025_n.jpg 960w, https:\/\/static-blogs.lasprovincias.es\/wp-content\/uploads\/sites\/4\/2012\/06\/181476_389341564446562_1564396025_n-300x200.jpg 300w, https:\/\/static-blogs.lasprovincias.es\/wp-content\/uploads\/sites\/4\/2012\/06\/181476_389341564446562_1564396025_n-768x511.jpg 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Estoy pensando ponerle a Whisky un tel\u00e9fono 900 para que me saque de pobre. Que nos anuncie el futuro, la loter\u00eda y cu\u00e1ndo subir\u00e1 el IVA.<\/p>\n<p>Con esa pasi\u00f3n absurda que nos entra cada vez que Espa\u00f1a juega a la pelotita por saber c\u00f3mo terminar\u00e1 el partido preguntando a un animal, yo estoy decidida a encumbrar a Whisky al estrellato canino. Sin bailar como el Jack Russell de la oscarizada The Artist y sin viajar a la luna como la maltratada Laika.<\/p>\n<p>La afici\u00f3n comenz\u00f3 con el pulpo Paul, que se dejaba caer sobre las urnas como quien asienta sus reales en cualquier roca marina. Pero hete aqu\u00ed que siempre lo hizo sobre la bandera del campe\u00f3n. Y nos subyug\u00f3 a todos. Y nos vimos, gentes adultas, hechas y derechas, curtidas en timos de estampitas y butaneros falsos, descre\u00eddas de dioses, elfos y p\u00f3cimas m\u00e1gicas, adictas a la aspirina y al\u00e9rgicas a las hierbas de la abuela Mato, tomando en serio la pose del cefal\u00f3podo.<\/p>\n<p>Como aquello pareci\u00f3 funcionar y hasta lloramos la p\u00e9rdida del Manolo marino, ahora nos hemos volcado con una nutria. Todo queda a remojo. Bajo el mar, bajo el mar, siempre hay ritmo, ritmo marino bajo el mar, como cantaba el cangrejo Sebasti\u00e1n.<\/p>\n<p>En la Eurocopa, es la nutria la que da pron\u00f3sticos. Se llama Maya, vive en Benalm\u00e1dena y vio venir el sufrimiento contra Francia porque no llegaba el gol. Tambi\u00e9n la nutria se lo pens\u00f3, remolone\u00f3, fue de aqu\u00ed para all\u00e1, intuyendo quiz\u00e1s los nervios de los aficionados espa\u00f1oles. Por fin, escogi\u00f3 la rojigualda. Y adquiri\u00f3 sin saberlo la condici\u00f3n de or\u00e1culo.<\/p>\n<p>No me extra\u00f1a que Grecia est\u00e9 como est\u00e1. Hecha unos zorros. Si de Delfos hemos pasado a las acrobacias de un habitante subacu\u00e1tico interpretadas libremente, nos merecemos la crisis que padecemos. De democracia, sobre todo. Puestos a creer en lo imposible, yo defiendo que lo nuestro es una maldici\u00f3n del Olimpo por dejar que Merkel secuestre a Europa. Eso son cosas de Zeus. \u00a1Y de nadie m\u00e1s!<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Estoy pensando ponerle a Whisky un tel\u00e9fono 900 para que me saque de pobre. Que nos anuncie el futuro, la loter\u00eda y cu\u00e1ndo subir\u00e1 el IVA. Con esa pasi\u00f3n absurda que nos entra cada vez que Espa\u00f1a juega a la pelotita por saber c\u00f3mo terminar\u00e1 el partido preguntando a un animal, yo estoy decidida a [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[83],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4325"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=4325"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4325\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=4325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=4325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=4325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}