{"id":4328,"date":"2012-06-29T23:20:21","date_gmt":"2012-06-29T21:20:21","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=4328"},"modified":"2012-06-29T23:20:21","modified_gmt":"2012-06-29T21:20:21","slug":"ni-habermas-ni-ratzinger","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/06\/29\/ni-habermas-ni-ratzinger\/","title":{"rendered":"Ni Habermas ni Ratzinger"},"content":{"rendered":"<p><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/06\/images-113.jpeg\"><img loading=\"lazy\" class=\"alignleft size-full wp-image-4329\" title=\"images-1\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/06\/images-113.jpeg\" alt=\"\" width=\"259\" height=\"194\" \/><\/a>Hace a\u00f1os, cuando Benedicto XVI a\u00fan no era Papa, se celebr\u00f3 en Alemania un magn\u00edfico debate entre el entonces cardenal Ratzinger y el fil\u00f3sofo J\u00fcnger Habermas. Era el encuentro de dos cabezas portentosas que conocen a fondo la filosof\u00eda de nuestro tiempo.<\/p>\n<p>Ayer, aqu\u00ed en Espa\u00f1a, se intent\u00f3 reproducir aquello a nuestra escala. Digo a nuestra escala no solo por la evidente distancia intelectual de los participantes con sus antecesores sino tambi\u00e9n por el enfoque y los temas de preocupaci\u00f3n.<\/p>\n<p>Los invitados eran el cardenal Ca\u00f1izares y Rodr\u00edguez Zapatero. Ninguno es fil\u00f3sofo ni dedica su tiempo al estudio y la reflexi\u00f3n. Ca\u00f1izares es te\u00f3logo y Zapatero, expresidente, un punto de partida muy distinto al alem\u00e1n.<\/p>\n<p>Eso se vio tambi\u00e9n en el enfoque. En el debate de Baviera, el n\u00facleo era el propio de una sociedad avanzada. All\u00ed se habl\u00f3 de los fundamentos de la democracia; de las bases de la regulaci\u00f3n social y de las fuentes de las que emanan los argumentos que le sirven de referencia.<\/p>\n<p>En el celebrado en \u00c1vila, ayer, la discusi\u00f3n se centr\u00f3 demasiado en la relaci\u00f3n entre la Iglesia y el poder y en la presencia del factor religioso en la vida pol\u00edtica.<a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/06\/images13.jpeg\"><img loading=\"lazy\" class=\"alignright size-full wp-image-4330\" title=\"images\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/06\/images13.jpeg\" alt=\"\" width=\"242\" height=\"208\" \/><\/a><\/p>\n<p>El giro es notable. Una cosa es reflexionar acerca de cu\u00e1l debe ser la pauta que regule la convivencia y, sobre todo, con qu\u00e9 justificaci\u00f3n tomar esa pauta y no una distinta y otra, aplicarlo a una realidad conflictiva reciente. Una cosa es buscar puntos de acuerdo y otra cruzar dos mon\u00f3logos.<\/p>\n<p>En el caso alem\u00e1n se buscaban par\u00e1metros \u00fatiles para toda sociedad contempor\u00e1nea; en el espa\u00f1ol, nos mir\u00e1bamos de nuevo el ombligo con reproches mutuos que, si bien no estaban en boca de los protagonistas, s\u00ed en un p\u00fablico bronco y falt\u00f3n, dedicado a silbar y a abuchear a Zapatero.<\/p>\n<p>Es un abismo. Triste abismo. Parece que seamos incapaces de elevarnos por encima de nuestras contiendas. Quiz\u00e1s es lo propio del debate entre pol\u00edticos y no entre pensadores.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hace a\u00f1os, cuando Benedicto XVI a\u00fan no era Papa, se celebr\u00f3 en Alemania un magn\u00edfico debate entre el entonces cardenal Ratzinger y el fil\u00f3sofo J\u00fcnger Habermas. Era el encuentro de dos cabezas portentosas que conocen a fondo la filosof\u00eda de nuestro tiempo. Ayer, aqu\u00ed en Espa\u00f1a, se intent\u00f3 reproducir aquello a nuestra escala. Digo a [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[40,58,136,148,149,187],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4328"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=4328"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4328\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=4328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=4328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=4328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}