{"id":4367,"date":"2012-07-10T21:37:26","date_gmt":"2012-07-10T19:37:26","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=4367"},"modified":"2012-07-10T21:37:26","modified_gmt":"2012-07-10T19:37:26","slug":"sangre-en-la-sangre","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/07\/10\/sangre-en-la-sangre\/","title":{"rendered":"Sangre en la sangre"},"content":{"rendered":"<p><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/07\/images-12.jpeg\"><img loading=\"lazy\" class=\"alignleft  wp-image-4370\" title=\"images-1\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/07\/images-12.jpeg\" alt=\"\" width=\"162\" height=\"152\" \/><\/a>Soy donante de sangre. Desde peque\u00f1a quise serlo. Lo aprend\u00ed de mi t\u00edo Pepe, el hermano de mi padre, que, como \u201chome bo\u201d, siempre lo fue. A\u00fan guardo un pin que me dio con una cruz azul y una gotita de sangre.<\/p>\n<p>Cuando voy a donar no siento que haga nada especial, aunque la campa\u00f1a del Centre de Transfusions nos presente como h\u00e9roes.<\/p>\n<p>Al contrario, devuelvo a la sociedad lo que hizo con amigos y familiares operados o accidentados. Si para ellos hubo sangre, quiero que haya para los dem\u00e1s.<\/p>\n<p>Sin embargo, ayer fue el primer d\u00eda en el que se me pas\u00f3 por la cabeza decir que no. Solo dur\u00f3 un segundo, sin duda. Pero existi\u00f3.<\/p>\n<p>Fue despu\u00e9s de leer en estas mismas p\u00e1ginas el llamamiento a reforzar las reservas de sangre ante la celebraci\u00f3n de \u201cbous al carrer\u201d.<\/p>\n<p>Digo que fue un segundo porque jam\u00e1s dejar\u00eda de ayudar a quien lo necesita, conscientemente, siendo tan f\u00e1cil, barata e indolora la forma de hacerlo como es donar un poco de sangre.<\/p>\n<p>En eso tienen suerte quienes se exponen a ser corneados por un toro, una conducta innecesaria, de riesgo voluntario y digna de ser erradicada en una Comunidad que presume de Bioparc pero consiente los \u201cbous al carrer\u201d. Incoherencias valencianas. Otra m\u00e1s.<\/p>\n<p><img loading=\"lazy\" class=\"alignright size-medium wp-image-4368\" title=\"images\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/07\/images3.jpg\" alt=\"\" width=\"300\" height=\"148\" \/><\/p>\n<p>Afortunadamente los donantes no elegimos a qui\u00e9nes dar nuestra sangre y eso incluye a quienes se exponen al da\u00f1o frente a un toro azuz\u00e1ndolo, estres\u00e1ndolo, poni\u00e9ndole fuego en la cabeza e incluso mat\u00e1ndolo lentamente.<\/p>\n<p>Esto s\u00ed es de h\u00e9roes, pues ayudamos a quienes consideramos autores de actos de barbarie. Lo hace la sociedad entera, la misma que ve c\u00f3mo las autoridades condicionan el acceso a tratamientos m\u00e9dicos en funci\u00f3n de la renta pero no de conductas de riesgo evitables.<\/p>\n<p>Quiz\u00e1s es hora de plantearlo: si se cobra el rescate al monta\u00f1ero imprudente y se multa al due\u00f1o de un pitbull sin bozal por su peligro potencial \u00bfpor qu\u00e9 no hacer lo mismo con quien no se protege de un toro por pura diversi\u00f3n?<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Soy donante de sangre. Desde peque\u00f1a quise serlo. Lo aprend\u00ed de mi t\u00edo Pepe, el hermano de mi padre, que, como \u201chome bo\u201d, siempre lo fue. A\u00fan guardo un pin que me dio con una cruz azul y una gotita de sangre. Cuando voy a donar no siento que haga nada especial, aunque la campa\u00f1a [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[22],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4367"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=4367"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4367\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=4367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=4367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=4367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}