{"id":4378,"date":"2012-07-12T21:00:48","date_gmt":"2012-07-12T19:00:48","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=4378"},"modified":"2012-07-12T21:00:48","modified_gmt":"2012-07-12T19:00:48","slug":"todos-somos-grecia-2","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/07\/12\/todos-somos-grecia-2\/","title":{"rendered":"Todos somos Grecia :-)"},"content":{"rendered":"<p><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/07\/fotonoticia_20120711103929_5001.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-4379 alignleft\" title=\"fotonoticia_20120711103929_500\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/07\/fotonoticia_20120711103929_5001.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/static-blogs.lasprovincias.es\/wp-content\/uploads\/sites\/4\/2012\/07\/fotonoticia_20120711103929_5001.jpg 500w, https:\/\/static-blogs.lasprovincias.es\/wp-content\/uploads\/sites\/4\/2012\/07\/fotonoticia_20120711103929_5001-300x200.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Hoy me siento m\u00e1s griega que nunca. Llamadme Helena, y perdonad que no ponga \u201cTroya\u201d en mi localizador pero el GPS no sabe d\u00f3nde para.<\/p>\n<p>\u201cTodos somos Grecia\u201d, podr\u00edamos llevar en nuestras camisetas. Es una posibilidad apasionante: arte, cultura, pensamiento, democracia, deporte&#8230; todo eso es Grecia.<\/p>\n<p>Ya s\u00e9 que hay algunos recortes y dificultades pero es por su bien. \u00bfC\u00f3mo, si no, van a estar apol\u00edneos y esbeltos cual disc\u00f3bolo de Mir\u00f3n? \u00bfAcaso la Venus de Milo es compatible con los excesos de la vida sedentaria y op\u00edpara? Rajoy vela por nuestra silueta. Es nuestro Dukan de cabecera.<\/p>\n<p>As\u00ed que nada de lloriqueos. El de ayer no fue un d\u00eda negro. Fue un pel\u00edn oscurito, pero no negro.<\/p>\n<p>Es verdad que en las tiendas no hay casi nadie pero es una ventaja: primero fueron los atascos y ahora son las colas. \u00a1La crisis acaba con los tumultos!<\/p>\n<p>Si entramos, nos saludan con alegr\u00eda los dependientes como si se les hubiera aparecido Dios. Si, adem\u00e1s, nos interesamos por lo que venden, hacen la ola y cantan a la vez. Pero si encima, sacamos la cartera con intenci\u00f3n de pagar, lloran de la emoci\u00f3n.<\/p>\n<p><img loading=\"lazy\" class=\"alignright size-medium wp-image-4380\" title=\"Ruzafa3\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/07\/Ruzafa31.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/static-blogs.lasprovincias.es\/wp-content\/uploads\/sites\/4\/2012\/07\/Ruzafa31.jpg 400w, https:\/\/static-blogs.lasprovincias.es\/wp-content\/uploads\/sites\/4\/2012\/07\/Ruzafa31-300x225.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Yo lo experiment\u00e9 ayer. Con tan mal cuerpo como me dej\u00f3 Rajoy, me fui decidida a comprar moldes para hacer bombones en mi intento por conseguir \u201cQUE NO ME AMARGUEN LA VIDA\u201d, como dec\u00eda un anuncio institucional a favor del az\u00facar. Me he propuesto poner az\u00facar a la crisis y al p\u00e1ncreas que le den morcilla (que le sentar\u00e1 de vicio, por cierto).<\/p>\n<p>Llevada de la emoci\u00f3n pastelera, cog\u00ed moldes para tartas, tartaletas y pudin. Y no me llev\u00e9 el soplete para hacer crema valenciana, por no ir cargada.<\/p>\n<p>Las chicas de la tienda que en ese momento, por hacer algo, pasaban el mocho, casi me hacen fallera mayor de la calle.<\/p>\n<p>Por eso decid\u00ed escribir esta columna. Porque la primera versi\u00f3n, que est\u00e1 en el blog, sali\u00f3 negra. Ceniza. Pero dije \u201cnunca mais\u201d. Pongamos sal y az\u00facar a esta crisis. Al menos, desde esta columna.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hoy me siento m\u00e1s griega que nunca. Llamadme Helena, y perdonad que no ponga \u201cTroya\u201d en mi localizador pero el GPS no sabe d\u00f3nde para. \u201cTodos somos Grecia\u201d, podr\u00edamos llevar en nuestras camisetas. Es una posibilidad apasionante: arte, cultura, pensamiento, democracia, deporte&#8230; todo eso es Grecia. Ya s\u00e9 que hay algunos recortes y dificultades pero [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[54,65,89,136,143],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4378"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=4378"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4378\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=4378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=4378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=4378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}