{"id":4431,"date":"2012-07-28T21:00:54","date_gmt":"2012-07-28T19:00:54","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=4431"},"modified":"2012-07-28T21:00:54","modified_gmt":"2012-07-28T19:00:54","slug":"campeones-sin-laurel","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/07\/28\/campeones-sin-laurel\/","title":{"rendered":"Campeones sin laurel"},"content":{"rendered":"<p><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/07\/estadio-olimpico-de-londres.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-4432\" title=\"estadio-olimpico-de-londres\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/07\/estadio-olimpico-de-londres.jpg\" alt=\"\" width=\"300\" height=\"216\" srcset=\"https:\/\/static-blogs.lasprovincias.es\/wp-content\/uploads\/sites\/4\/2012\/07\/estadio-olimpico-de-londres.jpg 416w, https:\/\/static-blogs.lasprovincias.es\/wp-content\/uploads\/sites\/4\/2012\/07\/estadio-olimpico-de-londres-300x216.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Hay algo en los Juegos Ol\u00edmpicos que nunca deja de sorprenderme. Cuando retransmiten tiro con arco, taekwondo o hockey sobre hierba concitan el inter\u00e9s de cientos de miles en nuestro pa\u00eds. Los medios narran lo sucedido, explican sus reglas y su aplicaci\u00f3n, y analizan la participaci\u00f3n de los atletas aunque no sean espa\u00f1oles. Al cabo de unos d\u00edas terminamos, incluso, sabiendo qui\u00e9nes son las grandes figuras de la halterofilia o de la lucha grecorromana.<\/p>\n<p>Sin embargo, el resto de la Olimpiada, es decir, de los cuatro a\u00f1os entre unos Juegos y otros, apenas si hay noticias sobre ese deporte y, por supuesto, no vemos ni una sola retransmisi\u00f3n.<\/p>\n<p>Ya s\u00e9 que no se puede comparar el impacto de un Mundial de f\u00fatbol con el de unos campeonatos mundiales de judo pero la pregunta es \u00bfpor qu\u00e9 no? No es en lo deportivo donde se encuentra la diferencia. En ese terreno, ambos son eventos de la misma intensidad y magnitud pero el Mundial o la Liga NBA son m\u00e1s notables que la cita ol\u00edmpica.<\/p>\n<p>El abismo est\u00e1 en el negocio, no el deporte. Y est\u00e1 por la influencia de la puesta en escena. Nos presentan Roland Garros o la Eurocopa como un acontecimiento digno de inter\u00e9s y de implicaci\u00f3n emocional. Eso activa nuestra apetencia y nos sentamos delante de la televisi\u00f3n. Gracias a ese gesto, la publicidad se interesa e inyecta dinero, lo que conseguir\u00e1 que se multiplique su aparici\u00f3n medi\u00e1tica. Y, as\u00ed, en un c\u00edrculo vicioso.<\/p>\n<p>A eso hay que a\u00f1adir la presencia de deportistas espa\u00f1oles. No hay m\u00e1s que recordar c\u00f3mo el inter\u00e9s por un deporte minoritario se ha acrecentado en nuestro pa\u00eds a partir de un campe\u00f3n: \u00c1ngel Nieto, Indur\u00e1in, Fernando Alonso o Nadal han hecho m\u00e1s por sus disciplinas que cualquier otra campa\u00f1a.<\/p>\n<p>Por eso me asombra que tengamos medallistas ol\u00edmpicos y no se les d\u00e9 visibilidad excepto cada cuatro a\u00f1os. Ahora que estamos necesitados de h\u00e9roes nacionales bien podr\u00eda cambiar la mentalidad.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hay algo en los Juegos Ol\u00edmpicos que nunca deja de sorprenderme. Cuando retransmiten tiro con arco, taekwondo o hockey sobre hierba concitan el inter\u00e9s de cientos de miles en nuestro pa\u00eds. Los medios narran lo sucedido, explican sus reglas y su aplicaci\u00f3n, y analizan la participaci\u00f3n de los atletas aunque no sean espa\u00f1oles. Al cabo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[60,83,147],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4431"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=4431"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4431\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=4431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=4431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=4431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}