{"id":4540,"date":"2012-09-21T22:55:35","date_gmt":"2012-09-21T20:55:35","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=4540"},"modified":"2012-09-21T22:55:35","modified_gmt":"2012-09-21T20:55:35","slug":"la-fatiga-de-la-hormiga","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/09\/21\/la-fatiga-de-la-hormiga\/","title":{"rendered":"La fatiga de la hormiga"},"content":{"rendered":"<p><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/09\/1348148055209.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-4541\" title=\"1348148055209\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/09\/1348148055209.jpg\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/static-blogs.lasprovincias.es\/wp-content\/uploads\/sites\/4\/2012\/09\/1348148055209.jpg 768w, https:\/\/static-blogs.lasprovincias.es\/wp-content\/uploads\/sites\/4\/2012\/09\/1348148055209-300x169.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>En los \u00faltimos d\u00edas no han sido pocos los amigos que me han repetido lo mismo respecto a Catalu\u00f1a: \u00a1que se independicen de una vez! Tambi\u00e9n los que tengo en el Principado dicen estar hartos de este tira y afloja. Yo misma estoy cansada de que Espa\u00f1a viva un dej\u00e0 v\u00fa constante desde hace dos siglos a cuenta de los nacionalismos. Y hasta Artur Mas lo dec\u00eda el otro d\u00eda hablando de \u201cla fatiga\u201d de Espa\u00f1a respecto a Catalu\u00f1a y viceversa.<\/p>\n<p>El president de la Generalitat catalana a\u00fan fue m\u00e1s lejos: se refiri\u00f3 al Norte respecto al Sur de Europa. Sin embargo hay algo en esas declaraciones que no me convence. En el mundo entero, el Norte mira con recelo al Sur que le atormenta con su pobreza. Porque \u00e9sa es la clave que no menciona Mas: los Nortes miran a los Sures con el desd\u00e9n de la hormiga a la cigarra. Se consideran trabajadores y serios frente a un sur vago y aprovechado. De esa forma, los movimientos de independencia, como la Liga Norte de Umberto Bossi en Italia, o la Catalu\u00f1a de Dur\u00e1n i Lleida censurando a los andaluces que pasan las horas muertas en el bar, lo que quieren es seguir siendo ricos ellos solos.<\/p>\n<p>Entiendo que pretendan evitar los abusos. La hormiga tiene todo el derecho a no financiar las juergas de la cigarra si \u00e9sta no aporta nada al conjunto, pero conviene revisar si el Sur tiene recursos, si tiene mecanismos para explotarlos y si la solidaridad debe seguir siendo un criterio de relaci\u00f3n entre comunidades.<\/p>\n<p>No es extra\u00f1o, pues, que est\u00e9n endureci\u00e9ndose los discursos nacionalistas con una crisis que exige esfuerzos. Todas las crisis hacen florecer proteccionismos y prejuicios y qu\u00e9 mejor que apelar a los fantasmas del sur pobre que se aprovecha del rico, aunque el rico haya malgastado. Se ve que si lo hace un propio se tolera mejor ya sea Millet, el tres per cent o la Banca Catalana. Es un discurso que alimenta rechazos y fatigas. Tambi\u00e9n de las hormigas del sur.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En los \u00faltimos d\u00edas no han sido pocos los amigos que me han repetido lo mismo respecto a Catalu\u00f1a: \u00a1que se independicen de una vez! Tambi\u00e9n los que tengo en el Principado dicen estar hartos de este tira y afloja. Yo misma estoy cansada de que Espa\u00f1a viva un dej\u00e0 v\u00fa constante desde hace dos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[118,126,136],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4540"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=4540"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4540\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=4540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=4540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=4540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}