{"id":4548,"date":"2012-09-22T17:33:51","date_gmt":"2012-09-22T15:33:51","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=4548"},"modified":"2012-09-22T17:33:51","modified_gmt":"2012-09-22T15:33:51","slug":"el-estadio-inacabado","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2012\/09\/22\/el-estadio-inacabado\/","title":{"rendered":"El estadio inacabado"},"content":{"rendered":"<p><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/09\/images.jpeg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-4549\" title=\"images\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2012\/09\/images.jpg\" alt=\"\" width=\"300\" height=\"134\" \/><\/a>Se plante\u00f3 un nuevo estadio de f\u00fatbol, habiendo dos en la ciudad. Y se lanzaron a construirlo. Se plante\u00f3 un Palau de Les Arts, existiendo otro de la M\u00fasica. Y se lanzaron a encarg\u00e1rselo al \u201cm\u00e1s grande\u201d, la Jurado de la arquitectura valenciana: Calatrava. Se plante\u00f3 un Palacio de Congresos, existiendo instalaciones de la Feria. Y tuvimos otra obra maestra para los libros de arte, Foster en esta ocasi\u00f3n. Ahora no sabemos c\u00f3mo pagar su ampliaci\u00f3n pero haberla, la habr\u00e1. Tampoco c\u00f3mo terminar el estadio pero \u00bfqui\u00e9n duda de que no quedar\u00e1 a medias?<\/p>\n<p>No me sirven las justificaciones de unos u otros sobre el arraigo del Valencia C.F. No dudo de ello ni de su valor emocional para los valencianos pero creo que algunos han utilizado \u00e9ste para operaciones de dudosa viabilidad, eficacia y rentabilidad. A los hechos me remito.<\/p>\n<p>Ya s\u00e9 que muchos se sentir\u00e1n afectados por lo que le pase al Valencia pero deber\u00edan sentirse peor por saber que fueron usados como escudos humanos. Quiz\u00e1s lo digo desde el desconcierto de tener ahorros en Bancaja ahora que compruebo c\u00f3mo se pusieron a disposici\u00f3n de una decisi\u00f3n incorrecta, temeraria e innecesaria. \u00bfEstaba para eso Bancaja? No quiero saberlo. Solo s\u00e9 que pierden quienes ponen cada domingo su alma en el club de su tierra. Ellos no sacan provecho de una parcela o una edificaci\u00f3n. Solo quieren que sus colores sean los mejores, los campeones y los que le den las alegr\u00edas que otros no saben ni pueden.<\/p>\n<p>En vez de dedicarse a eso, al deporte, los clubes de f\u00fatbol han jugado al monopoly y ahora est\u00e1n ahogados. Ahora bien, como de su aliento dependen tantas almas c\u00e1ndidas, las autoridades no pueden dejarlos caer. Las almas son votos, ya sabemos. As\u00ed pues, habr\u00e1 plazos, habr\u00e1 comprensi\u00f3n y habr\u00e1 dinero. Justo lo que no tienen quienes han de cumplir con la hipoteca, con el IBI o con los libros de texto. Tiran m\u00e1s dos votos que dos carretas, es evidente. Amunt, pues.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Se plante\u00f3 un nuevo estadio de f\u00fatbol, habiendo dos en la ciudad. Y se lanzaron a construirlo. Se plante\u00f3 un Palau de Les Arts, existiendo otro de la M\u00fasica. Y se lanzaron a encarg\u00e1rselo al \u201cm\u00e1s grande\u201d, la Jurado de la arquitectura valenciana: Calatrava. Se plante\u00f3 un Palacio de Congresos, existiendo instalaciones de la Feria. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[53,54,83,136],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4548"}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=4548"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/4548\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=4548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=4548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=4548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}