{"id":6811,"date":"2015-09-28T21:17:17","date_gmt":"2015-09-28T19:17:17","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=6811"},"modified":"2015-09-28T21:17:17","modified_gmt":"2015-09-28T19:17:17","slug":"que-piensen-ellos","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2015\/09\/28\/que-piensen-ellos\/","title":{"rendered":"Que piensen ellos"},"content":{"rendered":"<p><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2015\/09\/abe-convoca-elecciones-644x362.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-6816\" title=\"abe-convoca-elecciones--644x362\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2015\/09\/abe-convoca-elecciones.jpg\" alt=\"\" width=\"300\" height=\"168\" \/><\/a>Lo acaba de proponer Jap\u00f3n, ese pa\u00eds que hemos tenido durante d\u00e9cadas como ejemplo de progreso, de avance y de sacrificado esfuerzo colectivo. Su primer ministro ha pedido a las universidades p\u00fablicas que supriman las carreras human\u00edsticas, desde Historia a Derecho, Educaci\u00f3n o Arte, para centrarse en las t\u00e9cnicas. El argumento es la necesidad que tiene el pa\u00eds de ingenieros y cient\u00edficos frente a la inutilidad de literatos, fil\u00f3sofos o historiadores. La sugerencia no era tal habida cuenta de que la negativa de algunas autoridades acad\u00e9micas har\u00e1 reducir el dinero p\u00fablico destinado a las universidades rebeldes, como la de Tokio y la de Kioto que ya han anunciado su oposici\u00f3n a los planes del gobierno.<\/p>\n<p>El enfoque parece sensato a priori. Los recursos p\u00fablicos deben rentabilizarse al m\u00e1ximo. No es tiempo de perder dinero ni hacer inversiones sin resultados. Sin embargo, cuando se trata de la educaci\u00f3n ni la rentabilidad puede medirse ni las inversiones se pierden aun cuando, incluso, as\u00ed parezca. Hay estudiantes que pierden un a\u00f1o porque se despistan, se relajan y se dedican a vivir la vida durante el inicio de su carrera. Seg\u00fan ese planteamiento tan radical, habr\u00eda que invitarles a irse y no volver jam\u00e1s a la universidad. Sin embargo, algunos reaccionan tras un a\u00f1o \u201csab\u00e1tico\u201d y estudian, se esfuerzan y llegan m\u00e1s lejos de lo que cabr\u00eda esperar y mucho m\u00e1s que sus compa\u00f1eros. La raz\u00f3n es la semilla sembrada y germinada en su tiempo y a su modo.<\/p>\n<p>La educaci\u00f3n es esa semilla normalmente incontrolable. Pocos profesores pueden afirmar de forma rotunda qu\u00e9 \u201cresultado\u201d dar\u00e1 cada uno de sus alumnos. De lo que s\u00ed pueden estar seguros es de que existen los aparentes \u201cmilagros\u201d cuando ese estudiante que parec\u00eda ausente en clase dej\u00f3 que la semilla del inter\u00e9s, la curiosidad y el af\u00e1n de aprender fuesen asent\u00e1ndose en su interior. Es la cara m\u00e1s apasionante de la ense\u00f1anza, en ocasiones dura porque no se ve el fruto, pero a menudo grandiosa porque, con el tiempo, el buen docente sabe que ha depositado un germen de crecimiento que florecer\u00e1 cuando proceda y que ayudar\u00e1 a otro ser humano a ser mejor persona, mejor intelectual y mejor ciudadano. Ese enfoque no tiene nada que ver con la miop\u00eda de Jap\u00f3n -y de algunos responsables locales- que solo mide el saber por su utilidad inmediata. Su planteamiento tiene, tambi\u00e9n, una perversi\u00f3n m\u00e1s: en el fondo se usa a las personas y se les \u201cfabrica\u201d como piezas de un engranaje. Aunque aparente libertad, ese modelo universitario nip\u00f3n est\u00e1 m\u00e1s cerca del mundo feliz de Huxley que del avanzad\u00edsimo Imperio del Sol Naciente. Tampoco nosotros estamos alejados. Los \u00faltimos intentos por recortar esas materias en Bachillerato as\u00ed lo indican. M\u00e1s grave a\u00fan porque no se trata de formar a especialistas sino de ense\u00f1ar a pensar en chavales que est\u00e1n construyendo sus propios cimientos.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Lo acaba de proponer Jap\u00f3n, ese pa\u00eds que hemos tenido durante d\u00e9cadas como ejemplo de progreso, de avance y de sacrificado esfuerzo colectivo. Su primer ministro ha pedido a las universidades p\u00fablicas que supriman las carreras human\u00edsticas, desde Historia a Derecho, Educaci\u00f3n o Arte, para centrarse en las t\u00e9cnicas. El argumento es la necesidad que [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[54,56,66],"class_list":["post-6811","post","type-post","status-publish","format-standard","hentry","category-arsenico-por-diversion","tag-crisis","tag-cultura","tag-educacion"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/6811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=6811"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/6811\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=6811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=6811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=6811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}