{"id":6881,"date":"2015-11-18T23:04:30","date_gmt":"2015-11-18T21:04:30","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=6881"},"modified":"2015-11-18T23:04:30","modified_gmt":"2015-11-18T21:04:30","slug":"notre-dame","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2015\/11\/18\/notre-dame\/","title":{"rendered":"Notre Dame"},"content":{"rendered":"<p><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2015\/11\/soldados-francia-atentado-620x349.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-6882\" title=\"soldados-francia-atentado--620x349\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2015\/11\/soldados-francia-atentado.jpg\" alt=\"\" width=\"300\" height=\"168\" \/><\/a>Si hay un pa\u00eds que presume de laicista y que es ejemplo de una escrupulosa distancia entre las creencias personales y la esfera de lo p\u00fablico, es Francia. La Revoluci\u00f3n de 1789 enterr\u00f3 a todos los dioses que hasta el momento hab\u00edan presidido los altares de iglesias y capillas y hacia los que se hab\u00edan elevado las oraciones de los franceses durante siglos. Para Termidor, solo hab\u00eda una diosa, la diosa Raz\u00f3n, y esa dama no se llevaba nada bien con los que hasta entonces protagonizaban ritos y acaparaban inciensos.<\/p>\n<p>A pesar de su orgulloso laicismo, el Par\u00eds acribillado a balazos no se plante\u00f3 un espacio distinto para rezar y recordar a las v\u00edctimas de los atentados del viernes que Notre Dame. Una catedral cat\u00f3lica. All\u00ed no hubo quejas por elegirla como lugar de rezo comunitario. Es cierto que la ceremonia fue multirreligiosa, con sensibilidad hacia cristianos, jud\u00edos y musulmanes en justa correspondencia con la realidad demogr\u00e1fica francesa, pero bien pod\u00edan haberse alzado voces contrarias a un marco cat\u00f3lico como espacio de reuni\u00f3n. Nadie lo hizo. Notre Dame es Par\u00eds y es Francia. Y estos momentos son de dolor, de emoci\u00f3n y de muchas personas, con el coraz\u00f3n destrozado, que miran al cielo buscando respuestas, o como m\u00ednimo, consuelo.<\/p>\n<p>Frente a eso, todo lo dem\u00e1s suena a discurso vano, aprovechado, hip\u00f3crita y fuera de lugar. A quienes hoy lloran a hijas, novios, esposas o amigos les importa un bledo el debate demag\u00f3gico sobre un Estado laico. Quieren sentir que es toda Francia la que los arropa, que somos todos los europeos y todo hombre y toda mujer de buena voluntad quienes sufrimos con su dolor. Y, si entre todos esos \u2013la mayor\u00eda, desconocidos- hay quien eleva una oraci\u00f3n por su ser querido y por \u00e9l mismo, para que pueda retomar su vida y sentir algo de alivio en su infierno particular, bienvenida sea la oraci\u00f3n. Rece a quien rece y crea en quien crea. Francia no tiene los complejos de la \u00f1o\u00f1a Espa\u00f1a, siempre con remilgos anticlericales pasados de fecha. All\u00ed nadie llam\u00f3 asesino a Hollande ni se fue a las sedes de los partidos que apoyan la intervenci\u00f3n en Siria para gritar consignas de patio de colegio. Ni siquiera a Le Pen. No hay tiempo ni ganas de eso. La prioridad es acompa\u00f1ar a las familias, apoyar a las fuerzas de seguridad en su dif\u00edcil tarea, levantar la cabeza y cantar el himno nacional haciendo con ello una declaraci\u00f3n de principios. Es Francia quien se levanta, no cuatro patriotas desfasados. Seremos la naci\u00f3n m\u00e1s antigua de Europa, como se encargan de recordar a Catalu\u00f1a estos d\u00edas, pero tambi\u00e9n en la rancia Espa\u00f1a tenemos mucho que aprender. La unidad de estos d\u00edas no es incompatible con el sereno debate sobre las medidas que se deben adoptar ante la amenaza yihadista. Ni la oraci\u00f3n, de quien sea creyente, empa\u00f1a la laicidad estatal que no las rechaza todas, sino al contrario.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Si hay un pa\u00eds que presume de laicista y que es ejemplo de una escrupulosa distancia entre las creencias personales y la esfera de lo p\u00fablico, es Francia. La Revoluci\u00f3n de 1789 enterr\u00f3 a todos los dioses que hasta el momento hab\u00edan presidido los altares de iglesias y capillas y hacia los que se hab\u00edan [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[40,148,169,180],"class_list":["post-6881","post","type-post","status-publish","format-standard","hentry","category-arsenico-por-diversion","tag-catolicos","tag-religion","tag-terrorismo","tag-violencia"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/6881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=6881"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/6881\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=6881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=6881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=6881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}