{"id":6961,"date":"2016-01-20T21:47:23","date_gmt":"2016-01-20T19:47:23","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=6961"},"modified":"2016-01-20T21:47:23","modified_gmt":"2016-01-20T19:47:23","slug":"pactos-de-estado","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2016\/01\/20\/pactos-de-estado\/","title":{"rendered":"Pactos de Estado"},"content":{"rendered":"<p><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2016\/01\/sanchez-puig-k6QD-U2091879125686E-575x323@Las-Provincias.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-6983\" title=\"sanchez-puig-k6QD-U2091879125686E-575x323@Las Provincias\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2016\/01\/sanchez-puig-k6QD-U2091879125686E-575x323@Las-Provincias.jpg\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-content\/uploads\/sites\/4\/2016\/01\/sanchez-puig-k6QD-U2091879125686E-575x323@Las-Provincias.jpg 575w, https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-content\/uploads\/sites\/4\/2016\/01\/sanchez-puig-k6QD-U2091879125686E-575x323@Las-Provincias-300x169.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Ojal\u00e1 pongan tanto empe\u00f1o en lograr un acuerdo cuando se trate de los ciudadanos. Si son capaces de pasar d\u00edas y semanas; de no hablar ni trabajar por otra cosa; de marcar l\u00edneas rojas y de centrar todas sus energ\u00edas por conseguir acuerdos para constituir un grupo en el Congreso o un reparto de poder en la presidencia del gobierno, espero que se esfuercen con el mismo empe\u00f1o durante toda la legislatura. En una palabra, que cada vez que se presente un proyecto de ley, se sienten durante todo el tiempo necesario para arrancar un plan com\u00fan. Cualquier otra cosa pondr\u00e1 en evidencia lo que ya algunos se temen: que les importa m\u00e1s su poltrona y el reparto de recursos correspondiente que buscar lo mejor para la gente. Para toda, no solo para la propia.<\/p>\n<p>Un ejemplo es Pedro S\u00e1nchez, a punto de convertirse en la mejor representaci\u00f3n de la profec\u00eda autocumplida. \u201cProfec\u00eda autocumplida\u201d es un concepto de Robert Merton seg\u00fan el cual se anuncia una realidad no existente que se llega a cumplir porque el anuncio provoca que as\u00ed sea. En la mayor\u00eda de casos lo que sucede es que hablamos de algo como si existiera cuando, en realidad, no es as\u00ed. Termina si\u00e9ndolo porque, ante el temor de que suceda, hacemos lo imposible por que as\u00ed sea. A veces de forma inconsciente.<\/p>\n<p>El caso de S\u00e1nchez se pon\u00eda de manifiesto ayer cuando daba por amortizado a Rajoy. Dec\u00eda el l\u00edder socialista que Rajoy est\u00e1 \u201cagotado, aislado y acorralado por la corrupci\u00f3n\u201d. Que \u00e9l est\u00e9 agotado es posible; que lo est\u00e9 su proyecto, teniendo en cuenta que ha sido el m\u00e1s votado por los espa\u00f1oles, no parece que sea tan evidente. Que est\u00e9 acorralado por la corrupci\u00f3n es un primer intento de profec\u00eda autocumplida pues acorralar y acusar a alguien de estar acorralado al mismo tiempo resulta cuando menos sorprendente.<\/p>\n<p>Sin embargo, el ejemplo m\u00e1s claro es el tercer elemento: est\u00e1 aislado. Lo dice quien se niega a dialogar, a debatir para llegar a un acuerdo de legislatura y a tenerlo en cuenta para alcanzar el poder. Es decir, primero hacen un cord\u00f3n sanitario al PP y luego le reprochan que se a\u00edsle. Es cierto que Rajoy no parece estar dando pasos para renovar en el gobierno, pero resulta dif\u00edcil hacerlo cuando no solo lo excluyen sino que lo demonizan de tal forma que solo la posibilidad de incluirlo en las conversaciones es motivo de reproche social. Si al final S\u00e1nchez llega al gobierno, el pron\u00f3stico para ver acuerdos de tan larga gestaci\u00f3n y parto como los del trueque de esca\u00f1os y grupos es deprimente. \u00bfC\u00f3mo van a hacer un gran pacto de Estado sobre educaci\u00f3n o sobre la propia revisi\u00f3n constitucional en esas condiciones? Los pactos que necesita Espa\u00f1a no son de los afines sino de todos. Como m\u00ednimo, los mayoritarios y no por resucitar el bipartidismo sino porque se llaman \u201cmayoritarios\u201d al representar a la mayor\u00eda de los espa\u00f1oles. Al menos, de momento.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ojal\u00e1 pongan tanto empe\u00f1o en lograr un acuerdo cuando se trate de los ciudadanos. Si son capaces de pasar d\u00edas y semanas; de no hablar ni trabajar por otra cosa; de marcar l\u00edneas rojas y de centrar todas sus energ\u00edas por conseguir acuerdos para constituir un grupo en el Congreso o un reparto de poder [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-6961","post","type-post","status-publish","format-standard","hentry","category-arsenico-por-diversion"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/6961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=6961"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/6961\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=6961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=6961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=6961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}