{"id":6967,"date":"2016-01-30T21:52:55","date_gmt":"2016-01-30T19:52:55","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/mariajosepou\/?p=6967"},"modified":"2016-01-30T21:52:55","modified_gmt":"2016-01-30T19:52:55","slug":"presion-a-la-justicia","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2016\/01\/30\/presion-a-la-justicia\/","title":{"rendered":"Presi\u00f3n a la Justicia"},"content":{"rendered":"<p><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2016\/01\/colau-575x323.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-6991\" title=\"colau--575x323\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2016\/01\/colau.jpg\" alt=\"\" width=\"300\" height=\"168\" \/><\/a>El mejor seguro para una sociedad democr\u00e1tica es que los medios de comunicaci\u00f3n y la Justicia sean absolutamente independientes. Al menos, todo lo absoluto que permite un ser humano limitado. Cuando ambas esferas se ponen del lado del poderoso, la libertad queda maltrecha si no derrotada. Lo hemos visto en Argentina, con los Kirchner ahogando a la prensa cr\u00edtica o en Venezuela, convirtiendo el Tribunal Supremo en \u00faltimo basti\u00f3n del derrotado chavismo. Por eso resulta tan simb\u00f3lico que la infanta Cristina siga en el caso No\u00f3s. Lo contrario hubiera dado la sensaci\u00f3n de que la Justicia en Espa\u00f1a se plegaba a la conveniencia de la Jefatura del Estado. A todos beneficia que ayer la Audiencia de Palma rechazara aplicar la doctrina Bot\u00edn. La imagen del Rey queda impoluta, sin inmiscuirse, y los tribunales se muestran independientes, sin plegarse a ning\u00fan poder. El problema es que prime m\u00e1s lo ejemplarizante que la propia justicia. Quiz\u00e1s es lo sucedido, salvando las distancias, con Isabel Pantoja, que tanto se queja de un trato desigual. Por exceso de celo. Pudiera ser que estos personajes paguen no menos sino m\u00e1s de lo que lo har\u00eda un ciudadano an\u00f3nimo, precisamente por no serlo. En ese caso, su condici\u00f3n o fama ser\u00edan un lastre m\u00e1s que un beneficio, pero el resultado ser\u00eda igualmente injusto. De cualquier forma, lo sucedido ayer apuntala tanto a la Casa Real como a la Justicia, aunque salga absuelta.<\/p>\n<p>Lo curioso es que algunos dediquen muchos esfuerzos a celebrar la decisi\u00f3n de la Audiencia mientras pretenden presionar a otros \u00f3rganos de justicia. O, como m\u00ednimo, no parecen tener muy claras las distancias que el Poder Ejecutivo debe marcar respecto al Judicial. El ejemplo, tambi\u00e9n de ayer, viene de Catalu\u00f1a, cuya independencia medi\u00e1tica se ha puesto en entredicho en estos \u00faltimos a\u00f1os por v\u00eda de subvenciones, editoriales conjuntos y monotem\u00e1ticos. No es secundaria esa presi\u00f3n a los medios y a la Justicia \u2013con los alcaldes y sus varas de mando en la puerta- al mismo tiempo. Responde a la consideraci\u00f3n de que \u201cel proc\u00e9s\u201d est\u00e1 por encima de todo y todo \u201cen el pa\u00eds\u201d debe estar a su servicio.<\/p>\n<p>El Ayuntamiento de Barcelona, presidido por Ada Colau, decidi\u00f3 pedir el indulto para quienes acosaron a los parlamentarios catalanes en 2011. Sin duda es al Gobierno a quien se dirige pero lo hace poniendo en entredicho al Tribunal Supremo pues no hay motivo humanitario que justifique la petici\u00f3n sino ideol\u00f3gico. En esta ocasi\u00f3n, la justificaci\u00f3n del Ayuntamiento cuestiona la decisi\u00f3n del tribunal pues considera desproporcional la pena. Un argumento m\u00e1s llamativo si cabe considerando que se trata de un delito contra las instituciones y quien lo cuestiona es una instituci\u00f3n. La prudencia de la Casa Real, respetando con su silencio las decisiones judiciales, no es mero protocolo. Es un sano ejercicio de democracia.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El mejor seguro para una sociedad democr\u00e1tica es que los medios de comunicaci\u00f3n y la Justicia sean absolutamente independientes. Al menos, todo lo absoluto que permite un ser humano limitado. Cuando ambas esferas se ponen del lado del poderoso, la libertad queda maltrecha si no derrotada. Lo hemos visto en Argentina, con los Kirchner ahogando [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-6967","post","type-post","status-publish","format-standard","hentry","category-arsenico-por-diversion"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/6967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=6967"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/6967\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=6967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=6967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=6967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}