{"id":98,"date":"2010-05-08T13:20:23","date_gmt":"2010-05-08T13:20:23","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/mariajosepou\/?p=98"},"modified":"2010-05-08T13:20:23","modified_gmt":"2010-05-08T13:20:23","slug":"el-dudoso-topico","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/2010\/05\/08\/el-dudoso-topico\/","title":{"rendered":"El dudoso t\u00f3pico"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2010\/05\/6a00d83451586c69e200e551b73a6e8833-800wi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-99\" src=\"\/mariajosepou\/wp-content\/uploads\/sites\/4\/2010\/05\/6a00d83451586c69e200e551b73a6e8833-800wi.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Las elecciones en el Reino Unido apuntan dos conclusiones interesantes. La primera, que las <a href=\"http:\/\/www.lasprovincias.es\/prensa\/20100508\/mundo\/urnas-desinflan-aspiraciones-estrella-20100508.html\" target=\"_blank\" rel=\"external nofollow\">burbujas medi\u00e1ticas<\/a> son ficciones que enturbian la mirada y la segunda, que en tiempos de crisis, los ciudadanos se f\u00edan m\u00e1s de la derecha.<\/p>\n<p style=\"text-align: justify\">La campa\u00f1a y los resultados ingleses han evidenciado lo lejos que se encuentra el discurso medi\u00e1tico de la realidad cuando se trata de intenci\u00f3n de voto en momentos de incertidumbre. Fue la prensa la que encumbr\u00f3 a Nick Clegg al Olimpo del liderazgo pol\u00edtico solo porque en los debates televisivos pod\u00eda interpretar un papel que siempre es result\u00f3n: el de la r\u00e9plica al gobierno, por lo que ha hecho, y a la oposici\u00f3n, por lo que no ha hecho.<\/p>\n<p style=\"text-align: justify\">En esa tesitura, ser ocurrente, chispeante, incisivo o l\u00e1tigo de pol\u00edticos es f\u00e1cil y agradecido. Los liberal-dem\u00f3cratas de Clegg nunca han ocupado Downing Street de modo que no han tocado realidad y pueden crear preciosas pompas de jab\u00f3n con sus palabras, pues nadie vendr\u00e1 a reventarlas a cuenta de lo que decidieron cuando estuvieron en el poder. Ni Cameron ni Brown pod\u00edan usar ese truco.<\/p>\n<p style=\"text-align: justify\">Tras las debates, la prensa se dedic\u00f3 a hablar de Clegg como la gran esperanza, descubrimiento y promesa aunque solo lo fuera para las portadas period\u00edsticas. Una cosa es el show y otra, la factura de la luz de cada ciudadano. Con las cosas de comer no se juega, deben de haber pensado los brit\u00e1nicos, y han ido a buscar el refugio seguro. Ya har\u00e1n experimentos pol\u00edticos cuando de ellos no dependa el salario de cada d\u00eda.<\/p>\n<p style=\"text-align: justify\">Por eso resulta tan interesante la tendencia a protegerse en brazos de la derecha cuando hay crisis. Lo l\u00f3gico ser\u00eda decantarse por partidos de izquierdas, preocupados por las urgencias sociales. Sin embargo no parece que sea as\u00ed en ning\u00fan pa\u00eds de nuestro entorno.<\/p>\n<p style=\"text-align: justify\">Ante la crisis, los bolsillos parecen sentirse mejor con la derecha. Si es cierto el t\u00f3pico, los conservadores est\u00e1n m\u00e1s acostumbrados a buscar beneficios que a repartirlos igualitariamente. Eso significar\u00eda que nos fiamos m\u00e1s de quien sabe crear riqueza y nos conformamos con que la reparta un poco. Pero seguramente es solo un t\u00f3pico.<\/p>\n<p style=\"text-align: justify\"><strong>En sinton\u00eda<\/strong>: <a href=\"http:\/\/www.lasprovincias.es\/prensa\/20100508\/opinion\/parlamento-colgado-20100508.html\" target=\"_blank\" rel=\"external nofollow\">Un Parlamento &#8220;colgado&#8221;<\/a>.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Las elecciones en el Reino Unido apuntan dos conclusiones interesantes. La primera, que las burbujas medi\u00e1ticas son ficciones que enturbian la mirada y la segunda, que en tiempos de crisis, los ciudadanos se f\u00edan m\u00e1s de la derecha. La campa\u00f1a y los resultados ingleses han evidenciado lo lejos que se encuentra el discurso medi\u00e1tico de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[58,129,136,147],"class_list":["post-98","post","type-post","status-publish","format-standard","hentry","category-arsenico-por-diversion","tag-debates","tag-periodismo","tag-politicos","tag-reino-unido"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/98","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/comments?post=98"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/posts\/98\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/media?parent=98"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/categories?post=98"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/mariajosepou\/wp-json\/wp\/v2\/tags?post=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}